{"id":59819,"date":"2016-07-27T14:26:58","date_gmt":"2016-07-27T12:26:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/giangurgolo-max-mazzotta-scena-al-castello-svevo-cosenza\/"},"modified":"2023-01-17T12:10:11","modified_gmt":"2023-01-17T11:10:11","slug":"102012-giangurgolo-max-mazzotta-scena-al-castello-svevo-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/102012-giangurgolo-max-mazzotta-scena-al-castello-svevo-cosenza\/","title":{"rendered":"Il &#8221;Giangurgolo&#8221; di Max Mazzotta in scena al Castello Svevo di Cosenza"},"content":{"rendered":"<p><strong>Domani, alle\u00a021,00, al Castello Svevo arriva il Libero Teatro con \u201cGiangurgolo, principe di Danimarca\u201d, scritto e diretto da Max Mazzotta.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; In scena Francesca Gariano (Giangurgolo), Stefania Mangia (Zio Pantalone), Francesco Aiello (Bruzio e Dottor Pollone), Paolo Mauro (Taliano e Spettro) e Graziella Spadafora (Ofella e Pancrazio). Completano il cast l&#8217;Aiuto regia e organizzazione di Iris Balzano, i costumi di Merusca Staropoli, la scenografia Gianluca Salamone; responsabile tecnico e consolle luci Gennaro Dolce e il graphic designer Gianluca D&#8217;Andrea.\u00a0Pu\u00f2 <strong>Giangurgolo<\/strong> vestire i panni del pi\u00f9 tragico e nobile degli eroi shakespeariani, Amleto? La lettura non pu\u00f2 che essere in chiave comico-parodistica ed introduce lo spettatore ai temi della tragedia shakespeariana sfruttando le corde del grottesco e del riso liberatorio; meccanismo reso ancora pi\u00f9 efficace dalla caratterizzazione dei personaggi per mezzo dei diversi dialetti, che annullano la distanza fra pubblico e palcoscenico, rendendo gli eventi che accadono sulla scena riconoscibili e godibili anche ai giovanissimi. L&#8217;elaborazione del testo, infatti, trasposto linguisticamente e geograficamente in una Calabria immaginaria ma non troppo, offre occasioni di gioco e sperimentazione che possono risultare sorprendenti.\u00a0Il valore aggiunto di \u201cGiangurgolo, principe di Danimarca\u201d \u00e8 nella straordinaria ricchezza del linguaggio teatrale, che si serve contemporaneamente della forza espressiva delle <strong>maschere<\/strong>, della pantomima, del canto e della musica dal vivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domani, alle\u00a021,00, al Castello Svevo arriva il Libero Teatro con \u201cGiangurgolo, principe di Danimarca\u201d, scritto e diretto da Max Mazzotta.<\/p>\n","protected":false},"author":22,"featured_media":59820,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,34],"tags":[],"class_list":["post-59819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/59819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=59819"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/59819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/59820"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=59819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=59819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=59819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}