{"id":59925,"date":"2016-07-29T18:07:59","date_gmt":"2016-07-29T16:07:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/inaugurato-calabria-un-parco-avventura-calabria\/"},"modified":"2023-01-17T12:10:22","modified_gmt":"2023-01-17T11:10:22","slug":"102408-inaugurato-calabria-un-parco-avventura-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/102408-inaugurato-calabria-un-parco-avventura-calabria\/","title":{"rendered":"Inaugurato in Calabria un nuovo parco avventura"},"content":{"rendered":"<p><strong>Ottimo progetto per rilanciare il turismo ecosostenibile.<\/strong><\/p>\n<p><!--more--><br \/>\nPETILIA POLICASTRO (KR) &#8211; Il presidente della Regione Mario Oliverio ha inaugurato ieri sera, insieme al sindaco di Petilia Policastro Amedeo Nicolazzi e alla presenza di tantissimi cittadini, il Parco Avventura Principe. Si tratta di un bellissimo parco che offre <strong>percorsi acrobatici, equitazione, trekking, maneggio e passeggiate a cavallo, tiro con l&#8217;arco, spazi e giochi per bambini<\/strong>, ricettivita&#8217;, ristorazione, aree pic-nic e tantissime altre attivita&#8217; rivolte agli amanti del turismo ecosostenibile. Il parco sorge a 1400 metri sul livello del mare ed \u00e8 immerso in uno stupendo scenario costituito in gran parte da conifere e latifoglie secolari, nel cuore del Parco Nazionale della Sila, in un contesto naturale di elevata bellezza che presenta paesaggi mozzafiato.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Questa -ha detto Oliverio nel suo breve intervento di saluto ai presenti- e&#8217; davvero una bella iniziativa, che contribuisce a rendere attrattiva la nostra montagna. Un investimento che crea opportunita&#8217; di lavoro e che sicuramente contribuira&#8217; a migliorare le condizioni per determinare lo sviluppo e la crescita di quest&#8217;area. Gran parte del nostro territorio, circa l&#8217;80%, e&#8217; collinare e montano. Per guardare al futuro e per costruire una ipotesi di sviluppo sostenibile nella nostra regione non si puo&#8217; non partire da qui. <strong>La nostra regione non crescera&#8217; mai se l&#8217;80% del suo territorio continuer\u00e0 a rimanere isolato e abbandonato a se stesso<\/strong>. Per troppi anni queste aree sono state contrassegnate dall&#8217;abbandono e dallo spopolamento. Cio&#8217; ha prodotto danni incalcolabili al nostro territorio. Il grave dissesto geologico che caratterizza la nostra terra e&#8217; frutto anche dell&#8217; abbandono dell&#8217;uomo e dell&#8217;incuria.<\/p>\n<p>&nbsp;<\/p>\n<p>Bisogna invertire il trend e valorizzare al massimo questo nostro grande patrimonio naturale. Per farlo abbiamo riservato grande attenzione a questo discorso nella nostra programmazione comunitaria 2014-2020. Nel Por, per esempio, <strong>abbiamo costituito un fondo di aggiuntivo di 200 milioni di euro<\/strong> che sar\u00e0 operativo gi\u00e0 nelle prossime settimane. I protagonisti fondamentali della utilizzazione di queste risorse dovranno essere i territori. Non e&#8217; piu&#8217; il tempo delle singole opere &#8220;di paese&#8221; che non producevano nessuna ricaduta concreta sul territorio bisogna lavorare con una visione d&#8217;insieme. Guai a ripetere gli errori del passato in cui ogni singolo comune presentava il proprio progettino. Dobbiamo avere la capacita&#8217; di inserire i singoli interventi in un contesto pi\u00f9 grande.<\/p>\n<p>&nbsp;<\/p>\n<p>O la Calabria cresce tutta insieme, nel suo complesso, o non andremo da nessuna parte. La sfida che abbiamo davanti -ha concluso il presidente della Giunta regionale &#8211; \u00e8, dunque, quella di creare una forte sinergia tra Comuni, Regione e forze sociali, facendo interagire le diverse realt\u00e0 produttive ed attrattive presenti sul nostro territorio,<strong> mare-pianura-montagna, e creando proposte e pacchetti che mirino a soddisfare la domanda di un turismo ecosostenibile,<\/strong> di qualita&#8217; e rispettoso dell&#8217;ambiente e del territorio. Questo e&#8217; un piccolo esempio di come si puo&#8217; intervenire correttamente, rispettando il contesto in cui si colloca l&#8217;iniziativa e valorizzando al massimo le nostre risorse naturali&#8221;.<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\">\u00a0<\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/1320\">CLICCA QUI PER VISITARE IL SITO UFFICIALE<\/a><\/span><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/1320\">DEL NUOVO PARCO AVVENTURA CALABRESE<\/a><\/span><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Ottimo progetto per rilanciare il turismo ecosostenibile.<\/p>\n","protected":false},"author":22,"featured_media":59926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,34,13],"tags":[],"class_list":["post-59925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-magazine","category-qui-green"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/59925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=59925"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/59925\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/59926"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=59925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=59925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=59925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}