{"id":60047,"date":"2016-08-02T07:35:16","date_gmt":"2016-08-02T05:35:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rossano-verdi-centro-storico-contrade-momento-delle-soluzioni-concrete\/"},"modified":"2023-01-17T12:10:36","modified_gmt":"2023-01-17T11:10:36","slug":"102986-rossano-verdi-centro-storico-contrade-momento-delle-soluzioni-concrete","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/102986-rossano-verdi-centro-storico-contrade-momento-delle-soluzioni-concrete\/","title":{"rendered":"Rossano, carenza idrica nel centro storico e nelle contrade: &#8216;situazione peggiorata&#8217;"},"content":{"rendered":"<p><strong>&#8220;Non si pu\u00f2 andare avanti cos\u00ec, scrive Elisabetta Salatino &#8211; Verdi Centro Storico e Contrade, una citt\u00e0 che vuole essere vetrina di cultura nel mondo e proporsi sulla piazza del turismo che conta non pu\u00f2 avere ancora carenza idrica&#8221;.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>ROSSANO (CS) &#8211; Non soltanto il problema continua a permanere, ovviamente le responsabilit\u00e0 sono di natura tecnica e vanno ben oltre l\u2019amministrazione di turno, e nel <strong>Centro Storico<\/strong> la carenza di acqua \u00e8 un fatto preoccupante; addirittura registriamo un peggioramento della situazione, l\u2019acqua non solo viene <strong>staccata di notte<\/strong> come consuetudine (da terzo mondo ma consuetudine) ma scarseggia anche nelle ore diurne con tutti i disagi del caso che tutti possono immaginare.<\/p>\n<p>&#8220;Il problema &#8211; secondo quanto riporta la nota di Elisabetta Salatino del partito dei Versi &#8211; si sente in maniera pesante anche nelle contrade della zona orientale (Amica e Toscano in primis) e anche allo Scalo apprendiamo che le pessime condizioni della rete idrica iniziano a far danni consistenti. In attesa di capire cosa vorr\u00e0 fare <strong>l\u2019amministrazione Mascaro<\/strong>, insediatasi da poco e gi\u00e0 messa duramente alla prova con continui interventi e comunicati di scuse ai cittadini, ci rivolgiamo a tutte le istituzioni affinch\u00e9 inizino seriamente a pensare a soluzioni agevolative&#8221;.<\/p>\n<p>&#8220;In campagna elettorale abbiamo ribadito in lungo e in largo &#8211; conclude la Salatino &#8211; che <strong>bisogna slegarsi dalla Sorical<\/strong> e individuare nuove fonti di approvvigionamento, anche perch\u00e9 l\u2019acqua non arriva nelle case di molti cittadini ma le bollette si, e anche salate. Lanciamo dunque una proposta di una <strong>no tax area riservata ai quartieri che soffrono atavicamente di carenza idrica<\/strong> finch\u00e9 non si siano risolti in qualche modo i disagi che, lo ripetiamo, non sono degni di un paese civile che vorrebbe vivere di turismo. Sollecitiamo dunque amministratori e politica a rimboccarsi le maniche e a cercare di trovare soluzioni al problema&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Non si pu\u00f2 andare avanti cos\u00ec, scrive Elisabetta Salatino &#8211; Verdi Centro Storico e Contrade, una citt\u00e0 che vuole essere vetrina di cultura nel mondo e proporsi sulla piazza del turismo che conta non pu\u00f2 avere ancora carenza idrica&#8221;.<\/p>\n","protected":false},"author":21,"featured_media":60048,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-60047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/60047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=60047"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/60047\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/60048"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=60047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=60047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=60047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}