{"id":60354,"date":"2016-08-10T11:23:51","date_gmt":"2016-08-10T09:23:51","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/per-lanas-il-ponte-di-celico-e-sicuro-ma-quello-di-lsan-fili\/"},"modified":"2023-01-17T12:11:11","modified_gmt":"2023-01-17T11:11:11","slug":"104237-per-lanas-il-ponte-di-celico-e-sicuro-ma-quello-di-lsan-fili","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/104237-per-lanas-il-ponte-di-celico-e-sicuro-ma-quello-di-lsan-fili\/","title":{"rendered":"Silana &#8211; Crotonese: per l&#8217;Anas il ponte di Celico \u00e8 sicuro, ma quello di San Fili?"},"content":{"rendered":"<p><strong>Nessun dato tecnico a conferma delle rassicurazioni di Anas. Piogga di segnalazioni anche per un altro ponte della ss 107.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA \u2013 Subito interventi urgenti e straordinari sulla Silana &#8211; Crotonese. Il dibattito sulle condizioni di precariet\u00e0 del viadotto Cannavino, scaturito dalle segnalazioni di migliaia di utenti e cittadini della Presila e a seguito delle quali sono giunte le rassicurazioni da parte di Anas Calabria (purtroppo non suffragate da dati scientifici) sulla sicurezza dell\u2019opera, ha aperto una questione pi\u00f9 ampia sulla sicurezza della Statale 107. Infatti, mentre si discute per cercare una soluzione definitiva e risolutiva al problema strutturale del cavalcavia di Celico, emerge un altro problema, ancora una volta di natura statica, reale e documentato, sul ponte<strong> San Fili. A quanto pare, il viadotto mostrerebbe evidenti segni di usura dovuti alla mancanza di manutenzione.<\/strong> Nell\u2019attesa che si diano riscontri certi all\u2019utenza, sarebbe opportuno che gli enti preposti avviassero tutte le procedure precauzionali e di verifica tecnica per garantire massima sicurezza ad una delle arterie di collegamento pi\u00f9 importanti e strategiche della Calabria.<\/p>\n<p>&nbsp;<\/p>\n<p>A rilanciare ancora la questione \u00e8 il Segretario questore del Consiglio regionale, Giuseppe Graziano, che nelle ultime ore sta <strong>raccogliendo le denunce di numerosi cittadini che evidenziano una presunta pericolosit\u00e0 del ponte della SS107 che costeggia la cittadina di San Fili. &#8220;<\/strong>\u00c8 inammissibile che su una strada cos\u00ec importante e densamente trafficata come la SS 107 \u2013 dichiara il Consigliere regionale \u2013 non vengano effettuati, da anni, interventi di manutenzione straordinaria e di verifica statica dei numerosi cavalcavia e delle gallerie che compongono il tracciato. \u00c8 rispettabilissima l\u2019opinione dei tecnici che rassicurano sulle condizioni strutturali dell\u2019arteria, ma \u00e8 altrettanto comprensibile la preoccupazione degli utenti che quotidianamente percorrono la Silana crotonese e che osservano le numerose screpolature, le crepe dell\u2019asfalto e dei manufatti in cemento armato, cos\u00ec come le carenze degli impianti di sicurezza lungo la strada. Che sar\u00e0 anche sicura dal punto di vista statico anche se di questo non abbiamo la controprova scientifica, ma la Statale 107 senza dubbio non mette sicurezza a chi la percorre. Non a caso, e non credo si tratti di psicosi collettiva, in pi\u00f9 aree attraversate dall\u2019arteria vengono quotidianamente segnalate delle situazioni di criticit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>Che si intervenga, allora, &#8211; prosegue Graziano &#8211; ed in modo tempestivo. Senza anteporre alla risoluzione dei problemi l\u2019ormai solita giustificazione della carenza di finanziamenti.<strong> Di fronte alla sicurezza dei cittadini non ci sono motivazioni economiche che tengano.<\/strong> Anche perch\u00e9 esistono fondi strutturali comunitari dedicati all\u2019ammodernamento e alla messa in sicurezza delle strade, non sfruttati, che puntualmente, ogni anno, vengono rispediti al mittente. Abbiamo tra l\u2019altro \u2013 aggiunge Graziano \u2013 la fortuna di poter v<strong>antare in Calabria, a pochi passi dalla SS 107, un Ateneo che \u00e8 il fiore all\u2019occhiello per gli studi di ingegneria civile.<\/strong> In prima battuta, si potrebbero sfruttare le indiscusse ed elevate qualit\u00e0 tecniche organiche all\u2019Unical per poter avviare uno studio scientifico sulla stabilit\u00e0 della strada, quantomeno nei punti critici, e alla risultanza di queste analisi provvedere al reperimento dei fondi e alla consequenziale attivit\u00e0 di riqualificazione. Serve solo \u2013 conclude il Segretario questore \u2013 il solito buon senso, volont\u00e0 e capacit\u00e0 di programmare nell\u2019interesse dei cittadini&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nessun dato tecnico a conferma delle rassicurazioni di Anas. Piogga di segnalazioni anche per un altro ponte della ss 107.<\/p>\n","protected":false},"author":22,"featured_media":60355,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-60354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/60354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=60354"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/60354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/60355"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=60354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=60354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=60354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}