{"id":60386,"date":"2016-08-12T06:38:35","date_gmt":"2016-08-12T04:38:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/lega-pro-ecco-i-calendari-per-il-cosenza-subito-derby-contro-il-catanzaro\/"},"modified":"2023-01-17T12:11:15","modified_gmt":"2023-01-17T11:11:15","slug":"104389-lega-pro-ecco-i-calendari-per-il-cosenza-subito-derby-contro-il-catanzaro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/104389-lega-pro-ecco-i-calendari-per-il-cosenza-subito-derby-contro-il-catanzaro\/","title":{"rendered":"Lega Pro, ecco i calendari. Per il Cosenza subito derby contro il Catanzaro. Alla 5 e alla 6&#8242; gli altri due derby"},"content":{"rendered":"<p><strong>I rossoblu inizieranno la loro stagione domenica 28 agosto in trasferta a Catanzaro. Nella\u00a0seconda giornata\u00a0il Cosenza\u00a0ospiter\u00e0 il Taranto. I derby contro Vibonese e Reggina alla 5&#8242; e alla 6&#8242;. Si giocher\u00e0 anche a Santo Stefano e il 30 dicembre. Tre i turni infrasettimanali<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; \u00a0Sono stati presentati\u00a0ieri pomeriggio al\u00a0Teatro Regio di Parma i calendari del campionato di calcio di <strong>Lega Pro stagione 2016\/2017<\/strong>. La prima giornata si giocher\u00e0<strong> domenica\u00a028 agosto<\/strong>, l&#8217;ultima <strong>domenica 7 maggio 2017<\/strong>. Novit\u00e0 importati di questa stagione sono i due boxing day: le squadre, infatti, giocheranno anche nel periodo di fine anno con la disputa delle prime due giornate del girone di ritorno esattamente il <strong>26 ed il 30 dicembre 2016<\/strong>. Sono previsti<strong> tre turni infrasettimanali<\/strong>, due nel 2016, entrambi di mercoled\u00ec, il<strong> 14 settembre<\/strong> ed il <strong>7 dicembre<\/strong>. Sempre di mercoled\u00ec il terzo turno infrasettimanale il <strong>5 aprile 2017<\/strong>.<\/p>\n<p>Per il Cosenza la nuova stagione si apre subito con il derby di Calabria. Il 28 agosto rossoblu un trasferta a Catanzaro. Si torner\u00e0 al Marulla domenica prossima ospitando il Taranto (ripescato dalla serie D). Gli altri due derby arrivano consecutivamente alla 5&#8242; e alla 6&#8242; giornata quando i rossoblu ospiteranno la<strong> Vibonese<\/strong> in casa e poi la domenica successiva saranno al Granillo contro la <strong>Reggina<\/strong>. Per l gara contro\u00a0il Lecce dell&#8217;ex Meluso bisogner\u00e0 attendere la 13&#8242; giornata (13 novembre) con il Cosenza che viagger\u00e0 alla volta di Via del Mare. Contro il Catania si giocher\u00e0 al Marulla alla 16&#8242; giornata e infine i rossoblu chiuderanno il girone di andata in trasferta a Foggia.\u00a0Curiosit\u00e0:\u00a0il Cosenza nella prime\u00a08 giornate affronter\u00e0 ben 6 squadre tra ripescate e neopromosse. Il Presidente del Cosenza Calcio<strong> Eugenio Guarascio<\/strong> dal Teatro Regio di Parma ha commenta il calendario del Cosenza: &#8220;<em>E&#8217; stupendo partire con un derby sentito come quello con il Catanzaro. Speriamo che sia la volta buona!<\/em>&#8221;<\/p>\n<p><strong><span style=\"color: #ff0000;\">Queste tutte le gare del Cosenza nella stagione 2016\/2017<\/span><\/strong><\/p>\n<p>1 \u00a0<strong>Catanzaro &#8211; Cosenza (Andata 28 agosto \u2013 Ritorno 26 dicembre)<\/strong><br \/>\n2 \u00a0Cosenza &#8211; Taranto (Andata 4 settembre \u2013 Ritorno 30 dicembre)<br \/>\n3 \u00a0Matera &#8211; Cosenza (Andata 11 settembre \u2013 Ritorno \u00a022 gennaio)<br \/>\n4 \u00a0Cosenza &#8211; Melfi \u00a0(Andata 14 settembre \u2013 Ritorno 29 gennaio)<br \/>\n<strong>5 Cosenza &#8211; Vibonese (Andata 18 settembre \u2013 Ritorno 5 febbraio)<\/strong><br \/>\n<strong>6 \u00a0Reggina &#8211; Cosenza (Andata 25 settembre\u00a0\u2013 Ritorno 12 febbraio)<\/strong><br \/>\n7 \u00a0Cosenza &#8211; Virtus Francavilla (Andata 2 ottobre \u2013 Ritorno 19 febbraio marzo)<br \/>\n8 \u00a0Fondi &#8211; Cosenza (Andata 9 ottobre \u2013 Ritorno 26 febbraio)<br \/>\n9 Cosenza &#8211; Paganese (Andata 16 ottobre \u2013 Ritorno 5 marzo)<br \/>\n10 Fidelis Andria &#8211; Cosenza Andata (23 ottobre \u2013 Ritorno 12 marzo)<br \/>\n11\u00b0Juve Stabia &#8211; Cosenza (Andata 30 ottobre \u2013 Ritorno 19 marzo)<br \/>\n12 Cosenza &#8211; Casertana (Andata 6 novembre \u2013 Ritorno 26 marzo)<br \/>\n<strong>13 Lecce &#8211; Cosenza (Andata 13 novembre \u2013 Ritorno 2 aprile)<\/strong><br \/>\n14 Cosenza &#8211; Monopoli (Andata 20 novembre \u2013 Ritorno 5 aprile)<br \/>\n15 Siracusa &#8211; Cosenza (Andata 27 novembre \u2013 Ritorno 9 aprile)<br \/>\n16 Cosenza &#8211; Catania (Andata 4 dicembre \u2013 Ritorno 15 aprile)<br \/>\n17 Akragas &#8211; Cosenza (Andata 7 dicembre \u2013 Ritorno 23 aprile)<br \/>\n18 Cosenza &#8211; Messina (Andata 11 dicembre \u2013 Ritorno 30 aprile)<br \/>\n<strong>19 Foggia &#8211; Cosenza (Andata 18 dicembre \u2013 Ritorno 7 maggio)<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Questa invece\u00a0la prima giornata del Girone C di Lega Pro 2016\/2017 in programma domenica 28 agosto<\/p>\n<p><strong>Akragas\u00a0&#8211;\u00a0Vibonese<\/strong><br \/>\n<strong>Catania\u00a0&#8211;\u00a0Juve Stabia<\/strong><br \/>\n<strong>Catanzaro\u00a0&#8211;\u00a0Cosenza<\/strong><br \/>\n<strong>Foggia\u00a0&#8211;\u00a0Fidelis Andria<\/strong><br \/>\n<strong>Fondi\u00a0&#8211;\u00a0Reggina<\/strong><br \/>\n<strong>Melfi\u00a0&#8211;\u00a0Casertana<\/strong><br \/>\n<strong>Messina-\u00a0Siracusa<\/strong><br \/>\n<strong>Monopoli-\u00a0Lecce<\/strong><br \/>\n<strong>Paganese\u00a0&#8211;\u00a0Virtus Francavilla<\/strong><br \/>\n<strong>Taranto\u00a0&#8211;\u00a0Matera<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 CLICCA E SCARICA IL CALENDARIO COMPLETO<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/1351\" rel=\"attachment wp-att-104397\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-104397\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/08\/Calendario-Lega-pro.jpg\" alt=\"Calendario Lega pro\" width=\"698\" height=\"366\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Soste<\/strong>:<br \/>\nDomenica 8 Gennaio 2017<br \/>\nDomenica 15 Gennaio 2017<\/p>\n<p><strong>Turni infrasettimanali<\/strong>:<br \/>\nMercoled\u00ec 14 Settembre 2016<br \/>\nMercoled\u00ec 7 Dicembre 2016<br \/>\nMercoled\u00ec 5 Aprile 2017<\/p>\n<p><strong>Boxing Day<\/strong><br \/>\nLuned\u00ec 26 Dicembre 2016<br \/>\nVenerd\u00ec 30 Dicembre 2016<\/p>\n<p>Termine:<br \/>\nDomenica 7 Maggio 2017<\/p>\n<p><strong>PLAY OFF 1^ FASE : <\/strong><br \/>\nGara unica sola Andata<br \/>\nDomenica 14 Maggio 2017<\/p>\n<p><strong>2^ FASE: <\/strong><br \/>\nGare di Andata<br \/>\nDomenica 21 Maggio 2017<\/p>\n<p>Gare di Ritorno<br \/>\nMercoled\u00ec 24 Maggio 2017<\/p>\n<p><strong>FINAL EIGHT: <\/strong><br \/>\nQuarti di finale<br \/>\nGare di Andata<br \/>\nDomenica 28 Maggio 2017<\/p>\n<p>Gare di Ritorno<br \/>\nGioved\u00ec 1 Giugno 2017<\/p>\n<p>Semifinali *<br \/>\nMercoled\u00ec 7 Giugno 2017<\/p>\n<p>Finale *<br \/>\nDomenica 11 Giugno 2017<\/p>\n<p>* Gara unica in campo da designare<\/p>\n<p><strong>PLAY OUT <\/strong><br \/>\nGare di Andata<br \/>\nDomenica 21 Maggio 2017<\/p>\n<p>Gare di Ritorno<br \/>\nDomenica 28 Maggio 2017<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I rossoblu inizieranno la loro stagione domenica 28 agosto in trasferta a Catanzaro. Nella\u00a0seconda giornata\u00a0il Cosenza\u00a0ospiter\u00e0 il Taranto. I derby contro Vibonese e Reggina alla 5&#8242; e alla 6&#8242;. Si giocher\u00e0 anche a Santo Stefano e il 30 dicembre. Tre i turni infrasettimanali<\/p>\n","protected":false},"author":24,"featured_media":60387,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,20],"tags":[],"class_list":["post-60386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/60386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=60386"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/60386\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/60387"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=60386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=60386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=60386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}