{"id":60429,"date":"2016-08-14T04:30:58","date_gmt":"2016-08-14T02:30:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ferragosto-montaltese-con-giuliano-palma-in-concerto\/"},"modified":"2023-01-17T12:11:20","modified_gmt":"2023-01-17T11:11:20","slug":"104606-ferragosto-montaltese-con-giuliano-palma-in-concerto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/104606-ferragosto-montaltese-con-giuliano-palma-in-concerto\/","title":{"rendered":"Ferragosto a Montalto Uffugo con Giuliano Palma in concerto"},"content":{"rendered":"<p><strong>Il tradizionale concerto di Ferragosto con un ospite d&#8217;eccezione che far\u00e0 ballare e cantare tutti i presenti.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>MONTALTO UFFUGO (CS) &#8211; Ferragosto montaltese in musica, come da tradizione. Per il 15 agosto 2016, la Pro Loco Aufugum 2 in collaborazione con l\u2019Associazione Morfeo e con il patrocinio del Comune di Montalto Uffugo, ha scelto Giuliano Palma per trascorrere la serata in allegria. Un altro pezzo da novanta della musica italiana a Montalto Uffugo dunque, dopo che per lo scorso 14 luglio \u00e8 stata l\u2019Amministrazione comunale ad essersi assicurata la prestazione artistica del pluripremiato maestro Nicola Piovani.\u00a0Il cantautore milanese salir\u00e0 sul palco per presentare la sua ultima discografia che celebra presente e passato della musica italiana dal titolo \u201cGroovin\u201d insieme alle pi\u00f9 affermate cover da lui elaborate come <strong>\u201ctutta mia la citt\u00e0\u201d originariamente degli Equipe 84, \u201cMessico e Nuvole\u201d di Paolo Conte alle \u201c50mila lacrime\u201d di Nina Zilli.<\/strong>\u00a0I festeggiamenti del 15 agosto saranno accompagnati da tanta buona musica visto il bagaglio culturale di cui vanta Giuliano Palma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il tradizionale concerto di Ferragosto con un ospite d&#8217;eccezione che far\u00e0 ballare e cantare tutti i presenti.<\/p>\n","protected":false},"author":22,"featured_media":60430,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,565,571],"tags":[],"class_list":["post-60429","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-castrolibero-montalto","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/60429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=60429"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/60429\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/60430"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=60429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=60429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=60429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}