{"id":60794,"date":"2016-08-30T04:12:11","date_gmt":"2016-08-30T02:12:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/periferie-di-cosenza-abbandonate-diventeranno-le-nuove-porte-della-citta\/"},"modified":"2023-01-17T12:12:05","modified_gmt":"2023-01-17T11:12:05","slug":"106328-periferie-di-cosenza-abbandonate-diventeranno-le-nuove-porte-della-citta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/106328-periferie-di-cosenza-abbandonate-diventeranno-le-nuove-porte-della-citta\/","title":{"rendered":"Periferie di Cosenza abbandonate? Diventeranno le nuove &#8216;porte&#8217; della citt\u00e0"},"content":{"rendered":"<h4>Obiettivo prioritario i quartieri\u00a0<strong>Vaglio Lise, Serra Spiga, San Vito, via Popilia e Caricchio.<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; La riqualificazione delle periferie \u00e8 uno degli obiettivi strategici della seconda consiliatura Occhiuto. Un progetto che mira a reinserire i quartieri meno centrali nel circuito vitale della citt\u00e0. Nella ricerca delle fonti di finanziamento, l&#8217;Amministrazione comunale, attraverso l&#8217;Assessorato competente alla riqualificazione urbana guidato da Francesco Caruso, ha intercettato un bando della Presidenza del Consiglio dei Ministri, che d\u00e0 seguito al Programma Straordinario di Intervento per la riqualificazione urbana e la sicurezza delle periferie che, solo per il 2016, istituisce un Fondo di 500 milioni di euro.\u00a0<strong>Al bando, che per le citt\u00e0 capoluogo prevede un finanziamento massimo di 18 milioni di euro<\/strong>,<strong> il Comune di Cosenza partecipa prontamente trasferendovi il proprio progetto<\/strong> di \u201cValorizzazione dei quartieri e rigenerazione urbana: le periferie come le nuove Porte della Citt\u00e0 di Cosenza\u201d.\u00a0\u201cLa nostra idea di riqualificazione delle periferie, \u2013 \u00e8 il commento dell&#8217;Assessore Francesco Caruso \u2013 trova nell&#8217;adesione a questo bando la sua opportunit\u00e0 migliore perch\u00e9 vi si possa dare seguito nel segno della concretezza e della operativit\u00e0\u201d.<\/p>\n<h2><\/h2>\n<h2>IL PROGETTO DI RIQUALIFICAZIONE DELLE PERIFERIE DI COSENZA<\/h2>\n<p>Entrando nel merito, il progetto \u00e8 un insieme coordinato e ragionato di interventi inerenti la riqualificazione e la rigenerazione sociale-culturale-architettonica e strutturale, delle seguenti aree periferiche di Cosenza: <strong>Vaglio Lise, Serra Spiga, San Vito, via Popilia e localit\u00e0 Caricchio,<\/strong> <strong>in quanto caratterizzate da situazioni di marginalit\u00e0 economica e sociale, degrado edilizio e carenza di servizi. <\/strong>Una\u00a0riqualificazione che nel perseguire qualit\u00e0, attrattivit\u00e0 e rinnovato senso di appartenenza disegna un asse che va da Vaglio Lise con il recupero dell&#8217;area della stazione ferroviaria, rispetto al quale strategico \u00e8 il partenariato con il gruppo Ferrovie dello Stato gi\u00e0 formalizzato in un protocollo; percorre tutto il quartiere di via Popilia con interventi di riqualificazione diffusa; risale lungo viale Magna Grecia, per la realizzazione della cittadella dello sport e dunque la realizzazione del nuovo stadio comunale, per connettersi a San Vito con la rigenerazione dell&#8217;intero rione fino a Serra Spiga\/San Vito Alto, i due quartieri che forse pi\u00f9 di altri rappresentano la condizione di periferia.<\/p>\n<p>&nbsp;<\/p>\n<p>Significativa \u00e8, tra i partenariati, anche la presenza della Curia, prevedendo la riedificazione di un edificio di culto a via Popilia, Parrocchia di San Francesco Nuovo, e la realizzazione nell&#8217;area di Serra Spiga, Parrocchia di San Giuseppe, di un importante centro di aggregazione giovanile con annesso oratorio.\u00a0Nell&#8217;area di <strong>contrada Caricchio, luogo storico dell&#8217;accoglienza e della socialit\u00e0 grazie al Centro Sociale Gramna e al Villaggio del Fanciullo, l&#8217;intervento prevede, oltre la bonifica dell&#8217;intera zona<\/strong>, la riqualificazione dell&#8217;edificio dalla caratteristica forma di nave, per restituirgli la funzione di polo di accoglienza ed aggregazione sociale.\u00a0L&#8217;attuazione della strategia complessiva di intervento non pu\u00f2 prescindere da una serie di azioni diffuse, quelle da attivarsi nell&#8217;immediato e sempre nell&#8217;ambito del finanziamento, che sono ritenute necessaria ad innescare la scintilla della rigenerazione. Sono azioni che, in ognuno dei quartieri interessati, passano, per fermarci a qualche esempio, attraverso il recupero e riqualificazione di elementi esistenti, il ridisegno degli assi viari e pedonali e la valorizzazione del verde o, in alcuni casi, la realizzazione di edifici scolastici e ancora le riqualificazioni che assegnano a luoghi ed edifici nuove funzioni sociali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Obiettivo prioritario i quartieri\u00a0Vaglio Lise, Serra Spiga, San Vito, via Popilia e Caricchio.<\/p>\n","protected":false},"author":22,"featured_media":60795,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-60794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/60794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=60794"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/60794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/60795"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=60794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=60794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=60794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}