{"id":6087,"date":"2012-10-19T07:34:04","date_gmt":"2012-10-19T05:34:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=6087"},"modified":"2023-01-17T13:39:21","modified_gmt":"2023-01-17T12:39:21","slug":"2366-cosenza-al-via-il-festival-del-giallo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2366-cosenza-al-via-il-festival-del-giallo\/","title":{"rendered":"Cosenza: al via il Festival del Giallo"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 9pt; line-height: 115%; font-family: Arial, sans-serif; background-color: white;\"><strong>COSENZA<\/strong> &#8211; Inizia oggi,venerd\u00ec 19 ottobre, il Festival del Giallo, evento organizzato dalla Provincia di Cosenza e dal suo assessorato alla Cultura,&nbsp; dedicato a<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 9pt; line-height: 115%; font-family: Arial, sans-serif; background-color: white;\"> \u201cLe citt\u00e0 del Mistero\u201d.<span class=\"apple-converted-space\">&nbsp;<\/span><\/span><span style=\"font-size: 9pt; line-height: 115%; font-family: Arial, sans-serif;\"><span style=\"background-color: white;\">L\u2019apertura ufficiale da parte del presidente Mario Oliverio e dell\u2019assessore Maria Francesca Corigliano \u00e8 fissata alle 10,00 nell\u2019 Auditorium \u201cA. Guarasci\u201d del Liceo \u201cTelesio\u201d nella quale, subito dopo, si terr\u00e0&nbsp; una prima lezione di giallo diretta agli studenti.&nbsp;<\/span><span style=\"font-size: 9pt; line-height: 115%; background-color: white;\">Sar\u00e0 Patrizia Debicke Van Der Noot a parlare di \u201cStorie di gialli e gialli nella storia\u201d; la stessa scrittrice presenter\u00e0 poi con Cristina Marra, direttore artistico del Festival,&nbsp; il thriller storico \u201cL\u2019uomo dagli occhi glauchi\u201d (Corbaccio).&nbsp;<\/span><span style=\"background-color: white;\">Alle 11,30, nella&nbsp; Sala degli Stemmi Palazzo della Provincia, attesto incontro con \u201cBenvenuto Diabolik\u201d, per il quale lo scrittore&nbsp; Andrea Carlo Cappi, esperto del \u201cRe del crimine\u201d,&nbsp; introdurr\u00e0 al mondo del&nbsp; celebre personaggio del fumetto delle sorelle Giussani, cui \u00e8 dedicata \u201cUna vita in nero\u201d, mostra allestita nella Sala Commissioni del Palazzo di Piazza&nbsp; XV marzo, che ripercorre 50 anni di vita editoriale del famoso \u201ctascabile\u201d.&nbsp;<\/span><span style=\"font-size: 9pt; line-height: 115%; background-color: white;\">Nel pomeriggio, alle&nbsp; 16,30 nella Sala degli Specchi del Palazzo della Provincia , un pomeriggio con&nbsp;<\/span><span style=\"font-size: 9pt; line-height: 115%; background-color: white;\">presidente Mario Oliverio e l\u2019Assessore Maria Francesca Corigliano, il direttore artistico del Festival Cristina Marra, gli attori Nino Frassica, Flavio Insinna, gli autori Patrizia Debicke Van Der Noot, Andrea Carlo Cappi, Bruno Morchio, Francesco Recami, Paolo Roversi.&nbsp;<\/span><span style=\"font-size: 9pt; line-height: 115%; background-color: white;\">Nella stessa Sala provinciale, sul tema&nbsp; \u201cIndagini e misteri tra i carruggi e la casa di ringhiera \u201d,&nbsp; la presentazione di \u201c Colpi di coda\u201d (Garzanti) di Bruno Morchio e \u201cGli scheletri nell\u2019armadio\u201d(Sellerio) di Francesco Recami. Conduce l\u2019incontro la giornalista&nbsp; Barbara Marchio.&nbsp;<\/span><span style=\"font-size: 9pt; line-height: 115%; background-color: white;\">A seguire, Paolo Roversi racconta la Milano degli anni di piombo protagonista del suo romanzo \u201cMilano criminale\u201d(Rizzoli). Presenta Andrea Carlo Cappi.&nbsp;<\/span><span style=\"font-size: 9pt; line-height: 115%; background-color: white;\">In serata,&nbsp; alle 21,00, Auditorium \u201cA. Guarasci\u201d , Gialli in tv,&nbsp; \u201cIn due s\u2019indaga meglio\u201d&nbsp; talk show&nbsp; gli attori&nbsp; Flavio Insinna e Nino Frassica, interpreti delle fiction tv \u201cDon Matteo\u201d. Conduce il giornalista Michele Cucuzza.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Inizia oggi,venerd\u00ec 19 ottobre, il Festival del Giallo, evento organizzato dalla Provincia di Cosenza e dal suo assessorato alla Cultura,&nbsp; dedicato a<\/p>\n","protected":false},"author":22,"featured_media":6088,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-6087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=6087"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/6088"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=6087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=6087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=6087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}