{"id":6101,"date":"2012-10-19T09:46:01","date_gmt":"2012-10-19T07:46:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=6101"},"modified":"2023-01-17T13:39:21","modified_gmt":"2023-01-17T12:39:21","slug":"2373-melania-no-attenuanti-chiesto-ergastolo-parolisi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2373-melania-no-attenuanti-chiesto-ergastolo-parolisi\/","title":{"rendered":"Melania: no attenuanti, chiesto ergastolo Parolisi"},"content":{"rendered":"<p><strong>TERAMO<\/strong> &#8211; Ergastolo per Salvatore Parolisi.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Questa la pena chiesta dai Pm di Teramo per l&#8217;ex caporale degli alpini accusato di aver ucciso la moglie, Melania Rea.&nbsp;L&#8217;ha definito un puzzle con tanti elementi che tutti insieme compongono un quadro tipico del processo indiziario. Cos\u00ec il Pm di Teramo Davide Rosati ha spiegato il castello accusatorio nei confronti di Salvatore Parolisi, per il quale ha richiesto l&#8217;ergastolo per l&#8217;omicidio della moglie senza attenuanti generiche ma anzi con alcune aggravanti. Per l&#8217;accusa Salvatore Parolisi \u00e8 colpevole anche quindi di minorata difesa, crudelt\u00e0, e vilipendio aggravato dall&#8217;aver voluto depistare fuori di s\u00e9 la colpevolezza dell&#8217;omicidio. Quest&#8217;ultima accusa \u00e8 in funzione dell&#8217;aver creato tracce visibili a chi si fosse recato sul posto del delitto per depistare le indagini e sarebbero state fatte il giorno dopo il delitto. Sono queste aggravanti abbinate al reato di omicidio ad aver portato nonostante il rito abbreviato alla richiesta dell&#8217;ergastolo, perch\u00e9 secondo i Pm lo sconto di pena si effettua sulla possibile richiesta di isolamento diurno: ed \u00e8 questa infatti la parte abbonata con rito abbreviato.<\/p>\n<p>&#8220;E&#8217; quello che ci aspettavamo la richiesta di un ergastolo senza attenuanti&#8221;. Cos\u00ec l&#8217;avvocato della famiglia Rea, Mauro Gionni, all&#8217;uscita dell&#8217;aula il Pm Davide Rosati ha chiesto la pena massima per Salvatore Parolisi, reo, secondo l&#8217;accusa di aver ucciso la moglie Melania con 35 coltellate il 18 aprile 2011 nel bosco di Ripe di Civitella. Si \u00e8 conclusa cos\u00ec la prima parte della requisitoria odierna, pi\u00f9 tardi sar\u00e0 il turno della parte civile ossia proprio l&#8217;avvocato Gionni.<\/p>\n<p>Salvatore Parolisi e&#8217; arrivato al Tribunale di Teramo dove oggi sono iniziate le requisitorie del processo con rito abbreviato per l&#8217;omicidio di Melania Rea, la 29enne campana uccisa il 18 aprile 2010 nel bosco di Ripe di Civitella con 35 coltellate. Oggi nell&#8217;aula Falcone-Borsellino sara&#8217; il turno della pubblica accusa con i Pm Davide Rosati e Greta Aloisi a cui seguira&#8217; la parte civile dell&#8217;avvocato Mauro Gionni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TERAMO &#8211; Ergastolo per Salvatore Parolisi.<\/p>\n","protected":false},"author":22,"featured_media":6102,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16,5],"tags":[],"class_list":["post-6101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=6101"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6101\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/6102"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=6101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=6101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=6101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}