{"id":6123,"date":"2012-10-19T12:23:14","date_gmt":"2012-10-19T10:23:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=6123"},"modified":"2023-01-17T13:39:23","modified_gmt":"2023-01-17T12:39:23","slug":"2385-gentile-mio-pdl-su-stabilizzazione-precari-sanita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2385-gentile-mio-pdl-su-stabilizzazione-precari-sanita\/","title":{"rendered":"Gentile, mio pdl su stabilizzazione precari sanita&#8217;"},"content":{"rendered":"<p style=\"text-align: justify;\">(ASCA) &#8211;<em>COSENZA<\/em> &#8211; &#8221;Ho inviato ai capigruppo di maggioranza del Consiglio regionale della Calabria la proposta di legge sulla stabilizzazione del precariato<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">della sanita&#8217;: sono certo che essi sapranno apprezzare il testo e condividerlo con i colleghi dell&#8217;opposizione per risolvere secondo i dettami costituzionali una questione assai delicata&#8221;. Lo afferma, in una nota, il senatore Antonio Gentile, vice coordinatore regionale vicario del Pdl.<br style=\"margin: 0px; padding: 0px; color: #383838; font-family: Arial, 'Times New Roman', serif; line-height: normal; background-color: #ffffff;\" \/><br style=\"margin: 0px; padding: 0px; color: #383838; font-family: Arial, 'Times New Roman', serif; line-height: normal; background-color: #ffffff;\" \/>&#8221;Mi appello al presidente Talarico -prosegue Gentile- affinche&#8217; questa proposta, agganciata alla normativa nazionale ed ai rilievi della Consulta, diventi al piu&#8217; presto legge consentendo a quanti hanno i titoli di poter effettuare i concorsi riservati delle stabilizzazioni. E&#8217; necessario &#8211; aggiunge Gentile &#8211; separare il destino di quanti hanno i titoli secondo le leggi 296 e 294 da quanti hanno iniziato a lavorare a tempo determinato successivamente.<br style=\"margin: 0px; padding: 0px; color: #383838; font-family: Arial, 'Times New Roman', serif; line-height: normal; background-color: #ffffff;\" \/><br style=\"margin: 0px; padding: 0px; color: #383838; font-family: Arial, 'Times New Roman', serif; line-height: normal; background-color: #ffffff;\" \/>Pasticci e confusioni, come gia&#8217; e&#8217; accaduto con la legge 1\/2009, sarebbero ancora una volta annullati dalla Corte Costituzionale vanificando qualsiasi sforzo: per questo mi appello alla sensibilita&#8217; di ogni singolo consigliere e alla competenza del presidente Talarico, dal quale attendo una risposta&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(ASCA) &#8211;COSENZA &#8211; &#8221;Ho inviato ai capigruppo di maggioranza del Consiglio regionale della Calabria la proposta di legge sulla stabilizzazione del precariato<\/p>\n","protected":false},"author":22,"featured_media":6124,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-6123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=6123"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/6124"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=6123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=6123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=6123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}