{"id":61396,"date":"2016-09-14T17:55:35","date_gmt":"2016-09-14T15:55:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/caos-provincia-breve-la-sentenza-sul-caso-occhiuto\/"},"modified":"2023-01-17T12:13:24","modified_gmt":"2023-01-17T11:13:24","slug":"109039-caos-provincia-breve-la-sentenza-sul-caso-occhiuto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/109039-caos-provincia-breve-la-sentenza-sul-caso-occhiuto\/","title":{"rendered":"Caos Provincia, a breve la sentenza sul \u201ccaso\u201d Occhiuto"},"content":{"rendered":"<h4><strong>L\u2019opposizione si sposta nell\u2019aula giudiziaria: Enrico Morcavallo difende Di Natale.<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>COSENZA \u2013 L\u2019udienza davanti al Tar c\u2019\u00e8 stata: <strong>Benedetto Carratelli<\/strong>, che difende <strong>Mario Occhiuto<\/strong>, ha incrociato le proprie armi con quelle, altrettanto valenti, di <strong>Enrico Morcavallo<\/strong>, figlio di <strong>Oreste<\/strong>, il presidente dell\u2019Ordine degli avvocati cosentino, e valente amministrativista. Per la sentenza, tuttavia occorre attendere ancora qualche giorno (i bene informati dicono due).<\/p>\n<div id=\"attachment_109044\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-109044\" class=\"wp-image-109044 size-full\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/09\/Mario-Occhiuto-presidente-Provincia-300x200.jpg\" alt=\"mario-occhiuto-presidente-provincia-300x200\" width=\"300\" height=\"200\" title=\"\"><p id=\"caption-attachment-109044\" class=\"wp-caption-text\">Mario Occhiuto<\/p><\/div>\n<p>Gi\u00e0: il ginepraio \u00e8 intricato e spinoso. Chi ha ragione? Occhiuto, reinsediatosi alla guida della Provincia dopo la rielezione, o <strong>Graziano Di Natale<\/strong>, il consigliere Pd di Paola, che sarebbe dovuto diventare (e restare) presidente al posto del silurato sindaco di Cosenza, in qualit\u00e0 di consigliere anziano?<\/p>\n<p>&nbsp;<\/p>\n<p>La verit\u00e0, pi\u00f9 che nel mezzo, \u00e8 in bilico. Infatti, e lo hanno statuito prima il Tar e poi il Consiglio di Stato, la nomina di <strong>Francesco Giuseppe Bruno<\/strong>, fatta da Occhiuto a febbraio a siluramento avvenuto, non \u00e8 stata legittima. Detto altrimenti: il sindaco di Cosenza e presidente della Provincia aveva nominato il consigliere coriglianese Bruno come suo vicepresidente al posto del dimissionario <strong>Lino Di Nardo<\/strong> che, essendo all\u2019epoca consigliere comunale di Cosenza, sarebbe decaduto assieme a Occhiuto in seguito allo scioglimento anticipato dell\u2019assise cittadina del capoluogo.<\/p>\n<p>&nbsp;<\/p>\n<p>Ci\u00f2 per evitare che l\u2019assemblea provinciale nominasse presidente il paolano Di Natale, tra l\u2019altro (secondo i soliti beneinformati) considerato all\u2019epoca vicino a <strong>Nicola Adamo<\/strong>. Per quanto ben cucinata, la ciambella non \u00e8 riuscita col buco: infatti, Occhiuto ha nominato Bruno subito dopo aver subito il golpe e poco prima di decadere. In una fase, cio\u00e8, in cui non sarebbe potuto andare oltre l\u2019ordinaria amministrazione.<\/p>\n<div id=\"attachment_109050\" style=\"width: 450px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-109050\" class=\"wp-image-109050 size-medium\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/09\/graziano_di_natale-440x219.jpg\" alt=\"graziano_di_natale\" width=\"440\" height=\"219\" title=\"\"><p id=\"caption-attachment-109050\" class=\"wp-caption-text\">Graziano Di Natale<\/p><\/div>\n<p>Infatti, la giustizia amministrativa ha agito di conseguenza: mentre Occhiuto era affaccendato in una campagna elettorale, rivelatasi trionfale anche grazie al suicidio politico altrui, Di Natale riesce a travolgere la decisione dell\u2019ex presidente. E la nomina di Bruno \u00e8 stata dichiarata illegittima. Ergo, Di Natale \u00e8 diventato presidente.<\/p>\n<div id=\"attachment_109051\" style=\"width: 228px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-109051\" class=\"wp-image-109051 size-medium\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/09\/BRUNOFrancesco-218x280.jpg\" alt=\"brunofrancesco\" width=\"218\" height=\"280\" title=\"\"><p id=\"caption-attachment-109051\" class=\"wp-caption-text\">Francesco Bruno<\/p><\/div>\n<p>Ma magari le cose fossero filate cos\u00ec lisce: in realt\u00e0 lo Statuto della Provincia non contempla espressamente la possibilit\u00e0 di conferire la presidenza al consigliere anziano. Ed ecco che, una volta rieletto, Occhiuto si \u00e8 reinsediato alla guida di ci\u00f2 che resta dell\u2019ente di piazza XV marzo. Il resto \u00e8 noto: irrisolta la questione amministrativa, i due contendenti, il presidente \u201crientrato\u201d e quello \u201cnominato\u201d dal Consiglio di Stato, si sono denunciati a vicenda davanti agli uomini della Questura, un po\u2019 come capitava nel medioevo tra papi e antipapi.<\/p>\n<div id=\"attachment_109052\" style=\"width: 290px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-109052\" class=\"wp-image-109052 size-medium\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/09\/Lino-Di-Nardo-280x280.jpeg\" alt=\"lino-di-nardo\" width=\"280\" height=\"280\" title=\"\"><p id=\"caption-attachment-109052\" class=\"wp-caption-text\">Lino Di Nardo<\/p><\/div>\n<p>E la questione, spinosissima, si ripete anche oggi: se passasse la linea Di Natale, tutti gli atti o quasi fatti da Occhiuto sarebbero illegittimi. Soprattutto, risulterebbe illegittima l\u2019indizione delle nuove elezioni, previste per il 23 ottobre.<\/p>\n<p>&nbsp;<\/p>\n<p>E il caos continua, perch\u00e9 nel frattempo le ragioni del diritto si sono incrociate con quelle della politica. Infatti, Enrico Morcavallo, eletto al Consiglio Comunale nella lista guccioniana \u201cGrande Cosenza\u201d, \u00e8 diventato uno degli esponenti di prima fila dell\u2019opposizione, dopo che il paoliniano <strong>Giovanni Cipparrone<\/strong> gli ha soffiato la presidenza della Commissione controllo e garanzia, a cui era stato designato dal Pd e non solo.<\/p>\n<p>&nbsp;<\/p>\n<p>Come a dire: la giustizia seguir\u00e0 il suo corso comunque, data la professionalit\u00e0 dimostrata da Morcavallo jr in questa ed altre occasioni. Ma in questa giustizia, qualunque sar\u00e0 l\u2019esito, la politica far\u00e0 capolino. Vincer\u00e0 il diritto, forse. Ma di sicuro non sar\u00e0 fatta chiarezza.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\"><strong>Mario Margheriti<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019opposizione si sposta nell\u2019aula giudiziaria: Enrico Morcavallo difende Di Natale.<\/p>\n","protected":false},"author":22,"featured_media":61397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-61396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/61396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=61396"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/61396\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/61397"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=61396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=61396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=61396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}