{"id":61398,"date":"2016-09-15T04:21:20","date_gmt":"2016-09-15T02:21:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/settembre-rendese-atteso-un-lungo-fine-settimana-ricco-eventi\/"},"modified":"2023-01-17T12:13:24","modified_gmt":"2023-01-17T11:13:24","slug":"109046-settembre-rendese-atteso-un-lungo-fine-settimana-ricco-eventi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/109046-settembre-rendese-atteso-un-lungo-fine-settimana-ricco-eventi\/","title":{"rendered":"Settembre rendese, atteso un lungo fine settimana ricco di eventi"},"content":{"rendered":"<h4>Big nazionali dello spettacolo e grandi artisti sul palco del centro storico rendese.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; Tutto pronto per il lungo week end di spettacoli, enogastronomia, poesia, jazz e lirica nel centro storico di Rende. Il borgo antico sar\u00e0 la magnifica location naturale degli eventi promossi dall&#8217;amministrazione comunale di Rende, Assessorato alla Cultura, nell&#8217;ambito del \u201cSettembre Rendese\u201d. Il teatro all&#8217;aperto con lo <strong>spettacolo di Teo Teocoli ,il 16, in Piazza degli Eroi, con uno show che si articoler\u00e0 tra cabaret, canzoni, cinema e tv.<\/strong> Sabato17, invece , l&#8217;attore Gianfranco Jannuzzo porter\u00e0 in scena, sempre in Piazza degli eroi, il suo \u201cRecital\u201d. Ma le vie, le chiese, le piazze della parte antica della citt\u00e0 di Rende, saranno animate da numerosi eventi programmati dall&#8217;Amministrazione insieme alle Associazioni del territorio. Il 16, prima dello show di Teocoli, la serata inizia con il convegno \u201cProdotto topico sapore tipico\u201d. Poi l&#8217;itinerario teatrale tra le strade del Borgo Antico, la citt\u00e0 del Sole con William Gatto. La pro loco, invece, propone anche quest&#8217;anno \u201cLa via dei Vini\u201d con le migliori cantine del territorio e degustazioni enogastronomiche. La musica, inoltre, con Ensamble musicale &#8211; Vocale, il Piccolo Musicista e il grande jazz con Groove Association che presenta \u201cSalvatore Russo Gipsy Jazz Trio\u201d. Sabato, invece, di scena il Gran Gal\u00e0 di Poesia &#8211; Rende in Versi, a cura dell&#8217;Associazione Gueci, attesissimo evento nazionale di arte poetica, giunto alla sesta edizione, che costituisce ormai un appuntamento irrinunciabile per gli \u201camanti della poesia\u201d poich\u00e9 fornisce la possibilit\u00e0 di conoscere ed apprezzare la produzione di eccellenti poeti e di riflettere sulle tematiche dell\u2019uomo contemporaneo. Non mancher\u00e0 la solidariet\u00e0 con la raccolta di beneficenza di materiale didattico, a cura dell&#8217;associazione Niki Aprile. La lirica, con \u201cUna voce poco fa\u201dcon il mezzosoprano Melinda Bernaudo e Francesco Silvestri al pianoforte.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-109069\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/09\/locandina-teatro-372x280.jpg\" alt=\"locandina-teatro\" width=\"312\" height=\"235\" title=\"\"><\/p>\n<p>Il cinema, con \u201cCiak si mangia\u201de la proiezione \u201cChef-la ricetta perfetta\u201d, a cura dell&#8217;Associazione Cinepresi. Il jazz, con Egidio Ventura Jazz threee\u201dLatin Project\u201d. Numerosi gli appuntamenti anche per Domenica. La grande musica lirica , con \u201cRecondite Armonie: il Divino in musica\u201d, a cura di Luigia Pastore, con Sarah Baratta, soprano, Luca Bruno, baritono, Stefano Tanzillo, tenore, Silia Valente, soprano, Federico Veltri, tenore, Andrea Bauleo, pianoforte. Arte e moda, invece, con lo spettacolo \u201cRendefashionday\u201d, Un evento full &#8211; immersion, organizzato da Franco Siciliano, Francesco Greco, Alfredo Bruno e Valentina Zinno, che fonde arte e moda, grazie alla presenza di personaggi illustri del settore. Nel corso della serata, la presentazione del libro \u2013 intervista del maestro orafo Gerardo Sacco, \u201cSono Nessuno! Il mio lungo viaggio tra arte e vita\u201d, scritto dal giornalista Francesco Kostner per i tipi di Rubettino. A commentare il libro, oltre agli autori, il direttore del Quotidiano del Sud, Rocco Valenti. <strong>E poi spazio alla moda. In passerella, le creazioni preziose del maestro orafo Gerardo Sacco, i gioielli delle dive, e la collezione luxury \u201cOrchidea\u201d<\/strong> 2016\/2017 dello special guest, lo stilista Gianni Sapone Couture. Non mancheranno, per\u00f2, le giovani promesse del fashion designer. Per le serate nel centro storico sar\u00e0 attivo il servizio navetta gratuito. In caso di pioggia gli spettacoli di Teo Teocoli e Gianfanco Jannuzzo si terranno al Cinema Teatro Garden di Rende.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-109067\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/09\/orari-bus-centro-storico-440x181.jpg\" alt=\"orari-bus-centro-storico\" width=\"790\" height=\"325\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Big nazionali dello spettacolo e grandi artisti sul palco del centro storico rendese.<\/p>\n","protected":false},"author":22,"featured_media":61399,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,571,44],"tags":[],"class_list":["post-61398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-in-evidenza","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/61398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=61398"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/61398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/61399"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=61398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=61398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=61398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}