{"id":61513,"date":"2016-09-17T10:46:08","date_gmt":"2016-09-17T08:46:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/nasconde-due-panetti-hashish-nel-marsupio-arrestato-35enne-cosenza\/"},"modified":"2023-01-17T12:13:37","modified_gmt":"2023-01-17T11:13:37","slug":"109551-nasconde-due-panetti-hashish-nel-marsupio-arrestato-35enne-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/109551-nasconde-due-panetti-hashish-nel-marsupio-arrestato-35enne-cosenza\/","title":{"rendered":"Nasconde due panetti di hashish nel marsupio, arrestato 35enne a Cosenza"},"content":{"rendered":"<p><strong>Il weekend \u00e8 appena iniziato cos\u00ec come l&#8217;attivit\u00e0 dei Carabinieri della Compagnia di Cosenza, volta in particolar modo\u00a0alla prevenzione e repressione dello spaccio di sostanze stupefacenti.<\/strong><!--more--><\/p>\n<p>COSENZA &#8211; Una lunga notte di lavoro per i carabinieri di Cosenza che hanno eseguito un servizio coordinato volto alla prevenzione e repressione dei reati in genere e in particolar modo quelli predatori e dello spaccio di droghe. Circa <strong>quindici pattuglie hanno setacciato la citt\u00e0 dei Bruzi<\/strong>, con posti di controllo e perquisizioni che hanno portato all\u2019arresto di un trentacinquenne per detenzione ai fini di spaccio di sostanze stupefacenti.<\/p>\n<p>In manette \u00e8 finito <strong>B.C., 35 anni, di Paterno Calabro<\/strong>, il quale a seguito di un controllo nel centro storico, \u00e8 stato perquisito e trovato in possesso di due panetti di hashish dal peso complessivo di<strong> 200 grammi<\/strong> che aveva nascosto all\u2019interno del suo marsupio. Il giovane \u00e8 stato pertanto dichiarato in stato di arresto e tradotto presso la propria abitazione in regime degli arresti domiciliari. Nell&#8217;ambito dei controlli sono state anche<strong> denunciate altre cinque persone<\/strong> per evasione, violazione degli obblighi della sorveglianza speciale e spaccio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il weekend \u00e8 appena iniziato cos\u00ec come l&#8217;attivit\u00e0 dei Carabinieri della Compagnia di Cosenza, volta in particolar modo\u00a0alla prevenzione e repressione dello spaccio di sostanze stupefacenti.<\/p>\n","protected":false},"author":22,"featured_media":61514,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-61513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/61513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=61513"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/61513\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/61514"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=61513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=61513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=61513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}