{"id":61615,"date":"2016-09-20T16:19:34","date_gmt":"2016-09-20T14:19:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/samuele-bersani-rinvia-concerto-cosenza\/"},"modified":"2023-01-17T12:13:49","modified_gmt":"2023-01-17T11:13:49","slug":"109995-samuele-bersani-rinvia-concerto-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/109995-samuele-bersani-rinvia-concerto-cosenza\/","title":{"rendered":"Samuele Bersani rinvia il concerto di Cosenza per problemi di salute"},"content":{"rendered":"<h4>Il noto cantante bolognese dovr\u00e0 stare al riposo per alcune settimane senza poter salire sul palco.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Samuele Bersani rinvia il tour a causa di un problema alle corde vocali. Il concerto previsto al Teatro Rendano si terr\u00e0 il 7 marzo.\u00a0\u201cCiao amici, scrivo qui per dirvi che purtroppo la nostra voglia di incontrarci dovr\u00e0 attendere ancora un po\u2019. <strong>Un piccolo problema ad una corda vocale mi obbliga ad un imprevisto riposo forzato.<\/strong> Sono per questo costretto a rimandare l&#8217;inizio del viaggio che aspetto di fare in vostra compagnia. Riguardo ai biglietti acquistati non cambia niente: il posto rimane lo stesso, con una nuova data. C\u2019\u00e8 anche la possibilit\u00e0 di chiedere il rimborso, nel caso in cui non possiate venire. Mi dispiace molto se questo in qualche modo pu\u00f2 causarvi del disagio. Spero davvero di avervi ancora accanto, e vi comunico gi\u00e0 dove poterci abbracciare! Samuele\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Questo il messaggio che Samuele Bersani ha postato sui social, comunicando direttamente ai fan il riposo al quale dovr\u00e0 attenersi per qualche settimana. L&#8217;artista rassicura il pubblico sulle sue condizioni e annuncia che il tour \u00e8 solo rinviato di qualche settimana.\u00a0<strong>La data prevista al Teatro Rendano di Cosenza il 29 ottobre \u00e8 stata rinviata al 7 marzo.\u00a0<\/strong>I biglietti acquistati restano validi per le nuove date. Chiunque volesse il rimborso potr\u00e0 richiederlo entro e non oltre il 31 dicembre 2016 presso il punto vendita dove \u00e8 stato effettuato l\u2019acquisto.\u00a0I biglietti acquistati online sul sito TicketOne o telefonicamente tramite i Call Center verranno rimborsati come da modalit\u00e0 regolamentata nei termini e condizioni di acquisto del sito www.ticketone.it.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il noto cantante bolognese dovr\u00e0 stare al riposo per alcune settimane senza poter salire sul palco.<\/p>\n","protected":false},"author":22,"featured_media":61616,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,571,34],"tags":[],"class_list":["post-61615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-in-evidenza","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/61615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=61615"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/61615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/61616"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=61615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=61615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=61615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}