{"id":61848,"date":"2016-09-26T16:22:48","date_gmt":"2016-09-26T14:22:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-mensa-scolastica-gratis-meno-abbienti\/"},"modified":"2023-01-17T12:14:16","modified_gmt":"2023-01-17T11:14:16","slug":"111060-la-mensa-scolastica-gratis-meno-abbienti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/111060-la-mensa-scolastica-gratis-meno-abbienti\/","title":{"rendered":"La mensa scolastica? \u00c8 gratis per i meno abbienti"},"content":{"rendered":"<h4><strong>Chi guadagna meno di 3.500 euro all\u2019anno non pagher\u00e0. La Commissione bilancio propone, l\u2019assessore Vigna approva<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>COSENZA \u2013 Sei povero, ma povero davvero? I componenti della <em>Commissione bilancio<\/em> di <em>Palazzo dei Bruzi<\/em> hanno gi\u00e0 quantificato questa povert\u00e0: 3.500 euro annui di reddito Isee. Non \u00e8 facilissimo rientrarci, perch\u00e9 occorre non aver intestato nulla, un altro po\u2019 neppure i vestiti. Se rientri in questo parametro e hai figli, c\u2019\u00e8 una sorpresa: non paghi la mensa scolastica.<\/p>\n<div id=\"attachment_95327\" style=\"width: 413px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-95327\" class=\"wp-image-95327 size-medium\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/06\/comune-di-cosenza-403x280.jpg\" alt=\"comune-di-cosenza\" width=\"403\" height=\"280\" title=\"\"><p id=\"caption-attachment-95327\" class=\"wp-caption-text\">Il municipio di Cosenza<\/p><\/div>\n<p>Lo ha proposto stamane la Commissione bilancio, presieduta da <strong>Giuseppe D\u2019Ippolito<\/strong>, su impulso dei suoi consiglieri di minoranza. La proposta, comunque, \u00e8 passata senza polemiche, la Commissione l\u2019ha fatta propria all\u2019unanimit\u00e0 e l\u2019ha girata all\u2019assessore competente <strong>Luciano Vigna<\/strong>, che ha dato l\u2019ok.<\/p>\n<div id=\"attachment_74317\" style=\"width: 383px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-74317\" class=\"wp-image-74317 size-medium\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/02\/luciano-vigna-373x280.jpg\" alt=\"luciano-vigna\" width=\"373\" height=\"280\" title=\"\"><p id=\"caption-attachment-74317\" class=\"wp-caption-text\">Luciano Vigna<\/p><\/div>\n<p>Cosa cambi rispetto al regime ancora vigente, derivante dall\u2019allegato inserito nel Bilancio di previsione dal commissario straordinario? In apparenza poco: i cittadini nella fascia max 3.500 euro annui dovrebbero pagare 10 euro al mese. Ma, se si considerano i criteri rigidi del reddito Isee, risparmiarli non \u00e8 poco.<\/p>\n<p style=\"text-align: right;\"><strong>m. m.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chi guadagna meno di 3.500 euro all\u2019anno non pagher\u00e0. La Commissione bilancio propone, l\u2019assessore Vigna approva<\/p>\n","protected":false},"author":22,"featured_media":61849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-61848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/61848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=61848"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/61848\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/61849"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=61848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=61848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=61848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}