{"id":62387,"date":"2016-10-10T08:52:07","date_gmt":"2016-10-10T06:52:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/presentato-nellaccademia-cosentina-le-due-facce-della-notte-benito-patitucci\/"},"modified":"2023-01-17T12:15:26","modified_gmt":"2023-01-17T11:15:26","slug":"113489-presentato-nellaccademia-cosentina-le-due-facce-della-notte-benito-patitucci","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/113489-presentato-nellaccademia-cosentina-le-due-facce-della-notte-benito-patitucci\/","title":{"rendered":"Presentato all&#8217;Accademia Cosentina &#8220;Le due facce della notte&#8221; di Benito Patitucci"},"content":{"rendered":"<p><strong>L&#8217;universo di una malattia, l&#8217;Alzheimer, raccontato in una storia commovente che racconta una patologia terribile e occulta che annulla il ricordo di una vita.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; &#8220;Le due facce della notte&#8221; raccontano la storia di una famiglia del sud Italia che decide di lasciare la terra d&#8217;origine per andare a vivere stabilmente al Nord per ragioni di lavoro. Un vissuto sereno che improvvisamente si trasforma per lasciare il posto ad una cicatrice impensabile, quella della mutevolezza dell&#8217;Essere e Non-Essere che si succedono l&#8217;un l&#8217;altro e si disperdono nelle profondit\u00e0 del pianeta del&#8217;Alzheimer. Nei giorni scorsi il <strong>romanzo di Benito Patitucci \u201cLe due facce della notte\u201d<\/strong> \u00e8 stato presentato al pubblico nella sala dell\u2019Accademia Cosentina, dove eccellenti relatori ne hanno illustrato il contenuto umano e le peculiarit\u00e0 descrittive.<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-113497 alignright\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/10\/LE-DUE-FACCE-della-notte-.jpg\" alt=\"le-due-facce-della-notte\" width=\"254\" height=\"388\" title=\"\"><\/p>\n<p>All\u2019amicale saluto dell\u2019avv. Ernesto d\u2019Ippolito, Presidente della prestigiosa e plurisecolare istituzione, indirizzato al pubblico presente, ai soci e all\u2019autore, ha fatto seguito l\u2019affascinante intervento della dott.ssa Assunta Morrone, preside dell\u2019Istituto Comprensivo di Mendicino, che ha esaltato le qualit\u00e0 descrittive dell\u2019autore (mettendo anche in giusto rilievo la sua notevolissima e apprezzata produzione letteraria); qualit\u00e0 che si mescolano efficacemente alla sua capacit\u00e0 di affrontare problematiche di notevole rilevanza umana con la delicatezza della poesia, tenendo ben presente \u2013 soprattutto e sempre \u2013 il rispetto per il lettore e per la sua sensibilit\u00e0 emotiva.<\/p>\n<p>Il Segretario Perpetuo dell\u2019Accademia Cosentina, <strong>Coriolano Martirano<\/strong>, dal canto suo, ha evidenziato la parte storica del romanzo di Patitucci, tracciando e intersecando le linee di un <strong>racconto<\/strong> fatto di <strong>migrazione, di adattamento<\/strong> e infine di scelta a concretizzare i propri sogni anche in una regione diversa da quella di origine.<\/p>\n<p>L\u2019Autore, ha espresso il suo sentito ringraziamento all\u2019Accademia, nella persona del Presidente d\u2019Ippolito, nonch\u00e9 agli egregi relatori, alla lettrice, all&#8217;accorta coordinatrice e, pi\u00f9 che doverosamente, ai presenti.<\/p>\n<p>La manifestazione, seguita con vivo interesse dal numeroso pubblico intervenuto, \u00e8 stata brillantemente coordinata dalla dott.ssa Alessandra Patitucci, ricercatrice presso il CNR-ISN di Piano Lago e figlia dell\u2019autore; mentre le letture sono state affidate alla bravissima e professionale Angela Gallo.<\/p>\n<h3>L&#8217;autore: Benito Patitucci<\/h3>\n<div id=\"attachment_113499\" style=\"width: 183px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-113499\" class=\" wp-image-113499\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/10\/2.jpg\" alt=\"Benito Patitucci\" width=\"173\" height=\"173\" title=\"\"><p id=\"caption-attachment-113499\" class=\"wp-caption-text\"><em>Benito Patitucci<\/em><\/p><\/div>\n<p>Nato a <strong>Lattarico<\/strong> in provincia di Cosenza, cosentino di adozione, \u00e8 stato un dinamico imprenditore nel campo della computergrafica, oggi in pensione.<strong> Giornalista pubblicista<\/strong>, ha collaborato e collabora a quotidiani e riviste culturali di vario orientamento, dirigendo inoltre un periodico da lui stesso fondato. E&#8217; <strong>socio<\/strong> ordinario della prestigiosa e plurisecolare <strong>Accademia Cosentina<\/strong>, presso la quale ha tenuto alcune interessanti conferenze.<\/p>\n<p>La sua produzione letteraria \u00e8 iniziata nel 1954, quando vede la luce la silloge poetica &#8220;<strong>Fermati un solo istante<\/strong>&#8220;; da allora \u00e8 proseguita con numerose altre pubblicazioni che toccano i pi\u00f9 disparati campi della letteratura: dalle novelle ai racconti, dalle fiabe ai romanzi, dalla storia alla saggistica, naturalmente senza trascurare la poetica. Non si contano gli articoli di interesse generale, cos\u00ec come quelli specifici di critica teatrale, di critica pittorica, nonch\u00e9 molte recensioni. Amante appassionato della natura, si interessa attivamente di trekking, di speleologia e di alpinismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;universo di una malattia, l&#8217;Alzheimer, raccontato in una storia commovente che racconta una patologia terribile e occulta che annulla il ricordo di una vita.<\/p>\n","protected":false},"author":22,"featured_media":62388,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[25],"tags":[],"class_list":["post-62387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libri"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/62387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=62387"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/62387\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/62388"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=62387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=62387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=62387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}