{"id":6241,"date":"2012-10-22T12:11:19","date_gmt":"2012-10-22T10:11:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=6241"},"modified":"2023-01-17T13:39:30","modified_gmt":"2023-01-17T12:39:30","slug":"2452-dimissioni-irrevocabili-della-presidente-della-pro-reggina","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2452-dimissioni-irrevocabili-della-presidente-della-pro-reggina\/","title":{"rendered":"Dimissioni irrevocabili della Presidente della Pro Reggina"},"content":{"rendered":"<p style=\"text-align: justify;\">A poche ore dalla vittoria ottenuta contro il MecoPotenza, arrivano le dimissioni irrevocabili rassegnate dal presidente della Pro Reggina 97<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Antonella Cappellaccio a seguito della situazione venutasi a creare venerd\u00ec scorso quando le ragazze hanno disertato l&#8217;allenamento per non aver ricevuto dalla societ\u00e0 quanto pattuito ad inizio stagione. &#8220;Sono arrivata al punto di rassegnare le dimissioni, che reputo irrevocabili, per via dei molti problemi che ogni giorno, da 15 anni a questa parte, devo affrontare, problemi che nascono dalle difficolt\u00e0 di guidare una societ\u00e0 dilettantistica, una realt\u00e0 che comporta parecchi sacrifici sia dal punto di vista organizzativo che dal punto di vista psicologico. Per questi ed altri motivi di carattere personale e privato non mi sento pi\u00f9 di andare avanti, adesso attender\u00f2 la ratifica del consiglio direttivo prima di abbandonare la carica&#8221;. La situazione in casa amaranto si fa molto seria, si rischia di mandare all&#8217;aria una stagione iniziata addirittura meglio di quella passata, conclusasi con la vittoria dello scudetto, tuttavia la problematica economica risulta essere il fardello principale che questa societ\u00e0 deve trasportare, un peso reso ancora pi\u00f9 grande dallo scioglimento del comune di Reggio Calabria che ha fatto venire meno gli accordi presi con l&#8217;amministrazione comunale debitrice nei confronti della Pro Reggina di una cospicua somma di denaro che sarebbe servita per finanziare tutte le spese stagionali compresi i rimborsi per le atlete, causa scatenante di questa profonda crisi. Risposte non se ne sono avute neanche da Regione e Provincia, e a questo punto vista situazioneche si sta sviluppando, il futuro della squadra reggina \u00e8 avvolto in un nuvolone sempre pi\u00f9 nero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A poche ore dalla vittoria ottenuta contro il MecoPotenza, arrivano le dimissioni irrevocabili rassegnate dal presidente della Pro Reggina 97<\/p>\n","protected":false},"author":22,"featured_media":6242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,5,20],"tags":[],"class_list":["post-6241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-old","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=6241"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/6242"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=6241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=6241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=6241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}