{"id":6249,"date":"2012-10-22T12:46:25","date_gmt":"2012-10-22T10:46:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=6249"},"modified":"2023-01-17T13:39:30","modified_gmt":"2023-01-17T12:39:30","slug":"2456-viabilita-a3-rispristinata-erogazione-carburante","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2456-viabilita-a3-rispristinata-erogazione-carburante\/","title":{"rendered":"Viabilita&#8217;: A3, ripristinata erogazione carburante"},"content":{"rendered":"<p><strong>COSENZA<\/strong> &#8211;&nbsp;(Adnkronos)<span style=\"color: #1a171b; font-family: 'Maven Pro'; font-size: 14px; line-height: 24px; text-align: justify;\"> &#8211; <\/span>L&#8217;Anas comunica che e&#8217; stata ripristinata, questa mattina, l&#8217;erogazione del carburante presso le stazioni<\/p>\n<p>  <!--more-->  <\/p>\n<p>di servizio di Frascineto Ovest e Cosenza Ovest in direzione sud e Rogliano su entrambe le carreggiate dell&#8217;Autostrada A3 Salerno-Reggio Calabria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211;&nbsp;(Adnkronos) &#8211; L&#8217;Anas comunica che e&#8217; stata ripristinata, questa mattina, l&#8217;erogazione del carburante presso le stazioni<\/p>\n","protected":false},"author":22,"featured_media":6250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-6249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=6249"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6249\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/6250"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=6249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=6249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=6249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}