{"id":62737,"date":"2016-10-17T16:26:53","date_gmt":"2016-10-17T14:26:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/lo-stadio-e-quasi-pronto-il-crotone-si-prepara-alla-prima-partita-in-casa\/"},"modified":"2023-01-17T12:16:07","modified_gmt":"2023-01-17T11:16:07","slug":"115083-lo-stadio-e-quasi-pronto-il-crotone-si-prepara-alla-prima-partita-in-casa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/115083-lo-stadio-e-quasi-pronto-il-crotone-si-prepara-alla-prima-partita-in-casa\/","title":{"rendered":"Lo stadio \u00e8 &#8216;quasi&#8217; pronto, il Crotone si prepara alla prima partita in casa"},"content":{"rendered":"<h4>Lavori in corso allo Scida di Crotone dopo l&#8217;ok della soprintendenza\u00a0archeologica della Calabria.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CROTONE &#8211; Per la Lega Calcio lo stadio ancora non \u00e8 agibile, ma Vrenna sostiene che a breve verr\u00e0 riaperto.\u00a0&#8220;Crotone-Napoli si giochera&#8217; allo Ezio Scida, abbiamo consegnato tutta la documentazione in giornata e aspettiamo solo l&#8217;ufficialita&#8217; che pero&#8217; \u00e8 solo una formalit\u00e0.<strong> E&#8217; normale che la Lega ancora oggi individui nello stadio di Pescara la sede di Crotone-Napoli<\/strong>, ma oggi la commissione si riunira&#8217; e comunichera&#8217; a tutti l&#8217;ufficialita&#8217;&#8221;. Lo ha dichiarato il presidente del Crotone Raffaele Vrenna, intervenuto ai microfoni di Radio Crc. &#8220;Lo Scida quanto puo&#8217; dare al Crotone? Tanto. E&#8217; importante anche perche&#8217; gia&#8217; due anni fa ci siamo salvati grazie al nostro stadio e proveremo a fare la stessa cosa quest&#8217;anno. Non possiamo permetterci di perdere la serie A e faremo di tutto per restarci&#8221; ha detto il numero uno della societa&#8217; calabrese. &#8220;Speravo che nella scorsa giornata di campionato vincessero Napoli e Crotone. Ieri abbiamo disputato un&#8217;ottima partita, meritavamo piu&#8217; punti, ma sono felice perche&#8217; ho visto una squadra attiva, pronta a combattere. Abbiamo tanti giovani in squadra e ragazzi che per la prima volta giocano in serie A, ma spero di affrontare ogni squadra alla pari, poi che vinca il migliore.<\/p>\n<p>&nbsp;<\/p>\n<p>Al di la&#8217; del nostro bilancio, se si potesse tornare indietro, tanti errori non si farebbero. Ma, la nostra filosofia e&#8217; quella di puntare sui giovani e dobbiamo aspettarli altrimenti non avrebbe senso. Se guardiamo anche al passato ci rendiamo contro che giocatori come Berardeschi, Cataldi, Florenzi con fiducia e pazienza sono esplosi e speriamo che anche questi ragazzi in rosa possano avere la stessa carriera&#8221;<strong>. Il futuro sulla panchina crotonese e&#8217; di Nicola:&#8221;La fiducia al tecnico e&#8217; confermata al 100%,<\/strong> di solito quando le cose non vanno bene il primo a pagarne le spese e&#8217; l&#8217;allenatore, ma noi utilizziamo un&#8217;altra filosofia. Facciamo finta che il nostro campionato inizi col Napoli, nel nostro stadio. Quella azzurra e&#8217; una grande squadra, faccio gli auguri a Milik di una pronta guarigione, ma i giocatori che sono in panchina sono all&#8217;altezza del Napoli per cui non sara&#8217; facile per noi. Anzi, sara&#8217; una battaglia sportiva e dovremo fare molta attenzione. Allo Scida deve essere una festa, sara&#8217; una data storica per il Crotone e spero che i napoletani possano venire in tanti&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lavori in corso allo Scida di Crotone dopo l&#8217;ok della soprintendenza\u00a0archeologica della Calabria.<\/p>\n","protected":false},"author":22,"featured_media":62738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-62737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/62737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=62737"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/62737\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/62738"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=62737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=62737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=62737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}