{"id":63085,"date":"2016-10-25T15:26:27","date_gmt":"2016-10-25T13:26:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/da-luglio-nuovo-collegamento-aereo-lamezia-varsavia\/"},"modified":"2023-01-17T12:16:50","modified_gmt":"2023-01-17T11:16:50","slug":"116704-da-luglio-nuovo-collegamento-aereo-lamezia-varsavia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/116704-da-luglio-nuovo-collegamento-aereo-lamezia-varsavia\/","title":{"rendered":"Da luglio si vola anche in Polonia. Nuovo collegamento Lamezia &#8211; Varsavia con Wizzair"},"content":{"rendered":"<p class=\"entry-title\"><strong>Partir\u00e0 il 2 luglio 2017 il nuovo volo per Varsavia operato dalla compagnia low cost Wizzair. Due voli a\u00a0settimana ed un&#8217;offerta sempre pi\u00f9 ampia\u00a0dall&#8217;aeroporto\u00a0di Lamezia Terme verso le principali\u00a0capitali europee<\/strong><!--more--><\/p>\n<p class=\"entry-title\">LAMEZIA TERME (CZ) -Partir\u00e0 il <strong>2 luglio 2017<\/strong> il nuovo volo per<strong> Varsavia<\/strong>\u00a0(aeroporto Modlin) operato dalla compagnia low cost <strong>Wizzair<\/strong> che, con due frequenze settimanali\u00a0amplia l\u2019offerta di collegamenti dall\u2019<strong>Aeroporto di Lamezia Terme<\/strong>. I voli, effettuati con A<strong>irbus 320 da 180 posti<\/strong> <strong>gi\u00e0 prenotatili sul sito della compagnia<\/strong>, saranno operativi fino al 2020. Sacal, ente gestore dello scalo lametino, dopo <a href=\"https:\/\/quicosenza.it\/news\/1519\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><strong>Budapest<\/strong><\/span><\/a> e <a href=\"https:\/\/quicosenza.it\/news\/1518\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><strong>Bucarest<\/strong><\/span><\/a>, si assicura una nuova e strategica tratta che incrementa l\u2019offerta dei voli dall&#8217;Aeroporto Internazionale di Lamezia Terme verso le <strong>grandi capitali europee<\/strong>.<\/p>\n<p class=\"entry-title\">Nell&#8217;arco di un mese Wizzair consolida la sua posizione sullo scalo di Lamezia e aggiunge, grazie agli ottimi risultati di prenotazioni ottenuti con Bucarest e Budapest, anche Varsavia. Si incrementa, dunque, in maniera significativa l\u2019offerta dei voli internazionali da Lamezia Terme verso l\u2019Europa dell\u2019Est. \u201c<em>Sacal rafforza la partnership con Wizzair e aggiunge un collegamento con una grande e rinomata capitale europea<\/em> &#8211; dichiara il presidente della Sacal, <strong>Massimo Colosimo <\/strong>&#8211;\u00a0<em>Dopo Bucarest e Budapest, Varsavia \u00e8 un altro obiettivo raggiunto, che si inserisce nella nostra strategia di sviluppo, orientata all\u2019apertura verso il mercato dell\u2019est Europa e finalizzato a creare un solido network di collegamenti internazionali. Una nuova risposta alla domanda crescente di nuove rotte cui Sacal cerca di venire incontro sempre col massimo impegno, cercando di diversificare l\u2019offerta in un mercato complesso e in costante evoluzione<\/em>\u201d.<\/p>\n<div id=\"attachment_116709\" style=\"width: 619px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-116709\" class=\"wp-image-116709 \" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/10\/modlin-airport.jpg\" alt=\"Modlin \u00e8 il secondo aeroporti di Varsavia. Si trova a Modlin, una frazione di Nowy Dw\u00f3r Mazowiecki, 40 km a nord-ovest di Varsavia\" width=\"609\" height=\"299\" title=\"\"><p id=\"caption-attachment-116709\" class=\"wp-caption-text\"><strong><em>Modlin \u00e8 il secondo scalo di Varsavia. Si trova 40 km a nord della capitale<\/em><\/strong><\/p><\/div>\n<p class=\"entry-title\">I voli per l&#8217;aeroporti di Varsavia Modlin, saranno operati con un moderno\u00a0Airbus A320 da 180 posti ed avranno frequenza bisettimanale, mercoled\u00ec e domenica, con <strong>partenza alle 18.15 da Varsavia e alle 21.10 da Lamezia Terme<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Partir\u00e0 il 2 luglio 2017 il nuovo volo per Varsavia operato dalla compagnia low cost Wizzair. Due voli a\u00a0settimana ed un&#8217;offerta sempre pi\u00f9 ampia\u00a0dall&#8217;aeroporto\u00a0di Lamezia Terme verso le principali\u00a0capitali europee<\/p>\n","protected":false},"author":22,"featured_media":63086,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571,1],"tags":[],"class_list":["post-63085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza","category-senza-categoria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/63085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=63085"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/63085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/63086"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=63085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=63085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=63085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}