{"id":63278,"date":"2016-10-28T14:08:27","date_gmt":"2016-10-28T12:08:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rifiuti-ecologia-oggi-festa-del-cioccolato-differente-regole-per-differenziare-correttamente\/"},"modified":"2023-01-17T12:17:16","modified_gmt":"2023-01-17T11:17:16","slug":"117469-rifiuti-ecologia-oggi-festa-del-cioccolato-differente-regole-per-differenziare-correttamente","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/117469-rifiuti-ecologia-oggi-festa-del-cioccolato-differente-regole-per-differenziare-correttamente\/","title":{"rendered":"Rifiuti, Ecologia Oggi: Festa del cioccolato &#8220;differente&#8221;, regole per differenziare correttamente"},"content":{"rendered":"<p><strong>Ecologia Oggi, in occasione della Festa del Cioccolato, ha predisposto tutte le attrezzature necessarie per differenziare in modo corretto. Ricorda, inoltre, le modalit\u00e0 per gli stand<\/strong><!--more--><\/p>\n<p>COSENZA &#8211; In occasione della festa del cioccolato, edizione 2016, la societ\u00e0 <strong>Ecologia Oggi SpA ha predisposto tutte le attrezzature necessarie per differenziare correttamente.<\/strong><\/p>\n<p>Sono stati posizionati <strong>100 carrellati differenti per tipologia e colore su tutto il percorso della manifestazione.<\/strong> Inoltre saranno presenti i dipendenti per informare e sensibilizzare sia i partecipanti, che gli stand che hanno aderito alla manifestazione ad effettuare correttamente la raccolta differenziata.<\/p>\n<p>A questi ultimi, infatti, sono stati consegnati dei <strong>kit di buste (azzurre e neutre) che dovranno utilizzare e depositare correttamente alla fine di ogni serata.<\/strong><\/p>\n<p>Si auspica pertanto ad una festa del cioccolato \u201cdifferente\u201d!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-117474 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/10\/eco3-440x247.jpg\" alt=\"eco3\" width=\"440\" height=\"247\" title=\"\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-117476 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/10\/eco5-158x280.jpg\" alt=\"eco5\" width=\"158\" height=\"280\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-117473 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/10\/eco2-158x280.jpg\" alt=\"eco2\" width=\"158\" height=\"280\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-117475 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/10\/eco4-440x247.jpg\" alt=\"eco4\" width=\"440\" height=\"247\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ecologia Oggi, in occasione della Festa del Cioccolato, ha predisposto tutte le attrezzature necessarie per differenziare in modo corretto. Ricorda, inoltre, le modalit\u00e0 per gli stand<\/p>\n","protected":false},"author":22,"featured_media":63279,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,70],"tags":[],"class_list":["post-63278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-quiecologia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/63278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=63278"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/63278\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/63279"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=63278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=63278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=63278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}