{"id":6368,"date":"2012-10-23T13:05:46","date_gmt":"2012-10-23T11:05:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=6368"},"modified":"2023-01-17T13:39:37","modified_gmt":"2023-01-17T12:39:37","slug":"2516-scuola-da-domani-nuove-mobilitazioni-studenti-in-italia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2516-scuola-da-domani-nuove-mobilitazioni-studenti-in-italia\/","title":{"rendered":"Scuola: da domani nuove mobilitazioni studenti in italia"},"content":{"rendered":"<p><span style=\"font-family: Arial, 'Trebuchet MS', sans-serif; font-size: 12px; line-height: 17px; background-color: #ffffff;\">(AGI) &#8211; <strong>ROMA<\/strong> &#8211; Domani, giovedi&#8217; e venerdi&#8217; ripartono le mobilitazioni degli studenti di scuole e universita&#8217;: dalle piazze del 12 ottobre di Napoli e Milano gli studenti hanno rilanciato la <\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p><span style=\"font-family: Arial, 'Trebuchet MS', sans-serif; font-size: 12px; line-height: 17px; background-color: #ffffff;\">mobilitazione in una tre giorni che avra&#8217; come tema cardine la &#8220;liberazione dei saperi&#8221;, partendo dall&#8217;appello pubblicato sul sito www.saperiliberi.it. Previste mobilitazioni in Puglia, Campania, Lazio, Toscana, Liguria, Lombardia, Piemonte. &#8220;Quello a cui abbiamo assistito da vent&#8217;anni a questa parte &#8211; spiegano in una nota gli studenti della Rete della conoscenza &#8211; con tagli alle risorse, aumento delle tasse universitarie e introduzione del contributo nelle scuole, entrata degli esterni e restrizione degli spazi di democrazia non e&#8217; altro che un processo di privatizzazione&#8221;.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(AGI) &#8211; ROMA &#8211; Domani, giovedi&#8217; e venerdi&#8217; ripartono le mobilitazioni degli studenti di scuole e universita&#8217;: dalle piazze del 12 ottobre di Napoli e Milano gli studenti hanno rilanciato la<\/p>\n","protected":false},"author":22,"featured_media":6369,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,34,5,53],"tags":[],"class_list":["post-6368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-magazine","category-old","category-ck20-scuola"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=6368"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6368\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/6369"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=6368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=6368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=6368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}