{"id":6374,"date":"2012-10-23T13:22:23","date_gmt":"2012-10-23T11:22:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=6374"},"modified":"2023-01-17T13:39:37","modified_gmt":"2023-01-17T12:39:37","slug":"2519-carmen-russo-aspetta-un-figlio-saro-mamma-a-53-anni-e-un-dono-di-dio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2519-carmen-russo-aspetta-un-figlio-saro-mamma-a-53-anni-e-un-dono-di-dio\/","title":{"rendered":"Carmen Russo aspetta un figlio: &#8220;Sar\u00f2 mamma a 53 anni, \u00e8 un dono di Dio&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>ROMA<\/strong> &#8211; &#8220;Io e mio marito Enzo Paolo diventeremo genitori a marzo. Sono al quarto mese di gravidanza&#8221;.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Lo annuncia Carmen Russo, in un&#8217;intervista esclusiva su &#8216;Chi&#8217; in edicola domani. &#8220;<span id=\"U313821139847sBE\">Lo so, ho 53 anni, ma che male c&#8217;\u00e8? Questo figlio \u00e8 un dono di Dio<\/span>. Era da un anno che io ed Enzo Paolo facevamo tentativi, ma era andata sempre male, poi a luglio la bella sorpresa. Nutrivo il desiderio di diventare mamma da sempre, ma il bambino non voleva arrivare in modo naturale, cos\u00ec sono ricorsa alla fecondazione assistita&#8221;.<\/p>\n<p style=\"text-align: justify;\">&#8220;So -aggiunge la ballerina- che alcuni pensano che alla mia eta&#8217; non avrei dovuto, ma ho voluto questo bimbo con tutta me stessa. In cuor mio faro&#8217; il massimo per vivere il piu&#8217; a lungo possibile, finche&#8217; avro&#8217; aria nei polmoni. Chi vuole uccidere la mia felicita&#8217; si faccia avanti&#8221;. E riguardo al nascituro, Carmen Russo racconta: &#8220;Non sappiamo ancora se e&#8217; maschio o se e&#8217; femmina, ma sul nome abbiamo le idee chiare: lo o la chiameremo con il nome di un santo al quale siamo devoti. Il mio unico rammarico? Ho dedicato troppo tempo al lavoro, sarebbe stato piu&#8217; leale e piu&#8217; logico pensare a un figlio dieci anni fa. Ma e&#8217; un evento positivo e chiedo di non giudicare me e mio marito per questo&#8221;, conclude.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #454545; font-family: Arial, Verdana, Tahoma; font-size: 14px; line-height: normal; background-color: #ffffff;\">&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; &#8220;Io e mio marito Enzo Paolo diventeremo genitori a marzo. Sono al quarto mese di gravidanza&#8221;.<\/p>\n","protected":false},"author":22,"featured_media":6375,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,41,34,5],"tags":[],"class_list":["post-6374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-intrattenimento","category-magazine","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=6374"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/6375"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=6374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=6374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=6374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}