{"id":6406,"date":"2012-10-24T07:33:38","date_gmt":"2012-10-24T05:33:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=6406"},"modified":"2023-01-17T13:39:39","modified_gmt":"2023-01-17T12:39:39","slug":"2542-noleggiavano-auto-di-lusso-e-le-facevano-sparire16-arresti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2542-noleggiavano-auto-di-lusso-e-le-facevano-sparire16-arresti\/","title":{"rendered":"Noleggiavano auto di lusso e le facevano sparire,16 arresti"},"content":{"rendered":"<p style=\"text-align: justify;\">(AGI) &#8211; <strong>ROMA<\/strong> &#8211; Noleggiavano auto di grossa cilindrata e poi le facevano sparire. Una banda di italiani, romeni e bulgari e&#8217; stata sgominata dalla Polizia Stradale di Viterbo dopo<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">un&#8217;indagine andata avanti per oltre un anno. Sedici le ordinanze di custodia cautelare in carcere e 11 indagati. Un traffico illecito su &#8220;larga scala&#8221; che andava avanti gia&#8217; da tempo e che assicurava ai membri dell&#8217;organizzazione introiti cosi&#8217; consistenti da diventare una vera e propria &#8220;professione&#8221;, stabile ed esclusiva. Le autovetture rintracciate dalla Polizia Stradale sono 25, per un valore commerciale complessivo di circa un milione di euro. La banda puntava a vetture di grossa cilindrata, regolarmente noleggiate in Italia ed in altri Stati dell&#8217;Unione Europea (Spagna, Olanda e Francia). All&#8217;indagine hanno contribuito anche l&#8217;Interpol e per l&#8217;arresto di alcuni componenti della banda, le Polizie di Romania, Bulgaria e Germania. Fondamentale e&#8217; risultata anche la collaborazione delle Polizie Stradali di Roma, Napoli, Cosenza, Isernia, L&#8217;Aquila ed Agrigento. A noleggiare le auto provvedevano dei &#8220;corrieri&#8221; che, raggiungendo dall&#8217;Italia (quasi sempre da Roma), con volo aereo, diverse localita&#8217; in Germania, Belgio, Spagna e Francia, si recavano presso le filiali delle piu&#8217; note societa&#8217; di autonoleggio per stipulare regolari contratti con cui entrare in possesso di autovetture di &#8220;gamma medio-alta&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(AGI) &#8211; ROMA &#8211; Noleggiavano auto di grossa cilindrata e poi le facevano sparire. Una banda di italiani, romeni e bulgari e&#8217; stata sgominata dalla Polizia Stradale di Viterbo dopo<\/p>\n","protected":false},"author":22,"featured_media":6407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16,5],"tags":[],"class_list":["post-6406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=6406"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/6407"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=6406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=6406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=6406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}