{"id":64408,"date":"2016-11-22T17:20:34","date_gmt":"2016-11-22T16:20:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/bussa-alla-porta-armato-bestemmiando-e-tenta-di-stuprare-due-ragazze\/"},"modified":"2023-01-17T12:19:32","modified_gmt":"2023-01-17T11:19:32","slug":"122375-bussa-alla-porta-armato-bestemmiando-e-tenta-di-stuprare-due-ragazze","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/122375-bussa-alla-porta-armato-bestemmiando-e-tenta-di-stuprare-due-ragazze\/","title":{"rendered":"Bussa al portone armato bestemmiando e tenta di stuprare due ragazze"},"content":{"rendered":"<h4>Le due donne, svegliate nel cuore della notte, hanno aperto la porta credendo si trattasse di un&#8217;emergenza.<\/h4>\n<p><!--more--><br \/>\nLAMEZIA TERME (CZ) &#8211; Notte di terrore per due ragazze magrebine.\u00a0Ha tentato di abusare di due ragazze minacciandole con una pistola a salve, ma \u00e8 stato bloccato ed arrestato dai carabinieri. Sono state le stesse vittime dell&#8217;aggressione ad allertare il 112 chiedendo disperatamente aiuto. Il fatto \u00e8 avvenuto a Lamezia Terme, dove <strong>due donne di nazionalit\u00e0 marocchina hanno raccontato di essere state svegliate nel cuore della notte dal suono insistente del campanello di casa.<\/strong> Alla porta un uomo che imprecava, urlava e bussava con forza quasi a voler sfondare l&#8217;ingresso. Preso coraggio e scese in strada per capire di cosa si trattasse si sono ritrovate di fronte l&#8217;uomo, un loro connazionale che non avevano mai visto prima, armato di pistola, che le minacciava cercando un approccio fisico. Spaventate sono riuscite a chiedere aiuto.<\/p>\n<p>&nbsp;<\/p>\n<p>Mentre una delle due, infatti, ha cercato di distrarre l&#8217;uomo in evidente stato di alterazione psico-fisica e che nel frattempo l&#8217;ha colpita ripetutamente tentando di palpeggiarla, l&#8217;altra e&#8217; riuscita a chiamare l&#8217;utenza di emergenza 112. I militari della Compagnia carabinieri di Lamezia Terme hanno raggiunto l&#8217;abitazione, nel quartiere Nicastro, e hanno bloccato l&#8217;uomo che, nel frattempo, si era disfatto dell&#8217;arma. Messe in sicurezza le due giovani straniere e <strong>trasportate in ospedale per le dovute cure, i militari sono riusciti a ritrovare l&#8217;arma nell&#8217;abitazione dell&#8217;uomo dopo aver atteso diversi minuti prima che aprisse la porta<\/strong>. In manette e&#8217; finito un venticinquenne, Syaf Mohammed, con l&#8217;accusa di tentata violenza sessuale aggravata e lesioni personali, mentre un cittadino italiano, proprietario dell&#8217;arma, e&#8217; stato denunciato in stato di libert\u00e0 per favoreggiamento personale. Dopo l&#8217;udienza di convalida, al cittadino marocchino \u00e8 stata applicata la custodia cautelare in carcere in attesa di giudizio.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le due donne, svegliate nel cuore della notte, hanno aperto la porta credendo si trattasse di un&#8217;emergenza.<\/p>\n","protected":false},"author":22,"featured_media":64409,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-64408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/64408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=64408"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/64408\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/64409"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=64408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=64408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=64408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}