{"id":64463,"date":"2016-11-24T05:20:17","date_gmt":"2016-11-24T04:20:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/clementine-antiviolenza-due-giorni-piazza-xi-settembre-cosenza\/"},"modified":"2023-01-17T12:19:39","modified_gmt":"2023-01-17T11:19:39","slug":"122589-clementine-antiviolenza-due-giorni-piazza-xi-settembre-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/122589-clementine-antiviolenza-due-giorni-piazza-xi-settembre-cosenza\/","title":{"rendered":"Clementine Antiviolenza e corsi di autodifesa i in piazza XI Settembre a Cosenza"},"content":{"rendered":"<h4>L&#8217;iniziativa nasce nel 2012 per ricordare Fabiana Luzzi\u00a0bruciata viva in un agrumeto di Corigliano Calabro, zona in cui vengono coltivate le clementine IGP.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Appuntamento in piazza XI settembre a Cosenza, domani Venerd\u00ec 25 Novembre dalle 10,00 alle 19,00 nella Giornata Internazionale contro la violenza alle donne, le imprenditrici agricole di Confagricoltura Donna Calabria rinnovano a Cosenza, la IV edizione dell\u2019iniziativa\u201cClementine Antivilolenza\u201c che si propone di devolvere l\u2019intero ricavato della vendita in piazza, delle Clementine IGP di Calabria, al Centro Contro la Violenza alle Donne Roberta Lanzino aderente alla rete nazionale D.i.Re che da molti anni opera nell\u2019accoglienza delle donne che subiscono violenze. L\u2019iniziativa nata nel 2012, in seguito all\u2019atroce delitto di Fabiana Luzzi, bruciata viva in un agrumeto di Corigliano Calabro, zona di alta vocazione per la produzione di Clementine IGP, da <strong>un&#8217;idea progettuale delle imprenditrici agricole di Confagricoltura Donna Calabria, che hanno deciso di assumersi un impegno di testimonianza contro il femminicidio<\/strong> con la consapevolezza che queste orrore non debba essere dimenticato, la memoria assume infatti un valore di forte responsabilit\u00e0 civile.<\/p>\n<p>&nbsp;<\/p>\n<p>Si \u00e8 inteso, attribuire un significato simbolico di Memoria della Violenza alla \u201cClementina\u201d, frutto di eccellenza del territorio, che in questa stagione \u00e8 all\u2019acme della sua produzione. <strong>La manifestazione negli anni ha incontrato largo consenso, non solo in Calabria ma in tutto il Paese dove \u00e8 stata ripresa anche da molte altre Regioni.<\/strong> Le imprenditrici di Confagricoltura Donna Calabria sono diventate cosi portatrici di un impegno forte nella lotta contro la violenza alle donne. All\u2019iniziativa quest\u2019anno si associa il Conservatorio di Cosenza, Stanislao Giacomoantonio, la cui orchestra di Sax, composta da 20 elementi, accompagner\u00e0 la vendita. La presenza dei giovani costituisce un esempio di grande rilevanza sociale perch\u00e9 \u00e8 da loro che dipende una nuova consapevolezza culturale del problema. Oltre al frutto, in piazza a partire dalle 10,00 e fino alle 19,00 verranno vendute anche le piantine di clementine, e le candele contenenti la stessa essenza a suggerire che in quel giorno vengano accese sul davanzale in segno di partecipazione. Presenti in piazza inoltre lo Scorpion Health Club e Teem Miura, per una lezione di difesa personale rivolta alle donne.<\/p>\n<p style=\"text-align: center;\">\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;iniziativa nasce nel 2012 per ricordare Fabiana Luzzi\u00a0bruciata viva in un agrumeto di Corigliano Calabro, zona in cui vengono coltivate le clementine IGP.<\/p>\n","protected":false},"author":22,"featured_media":64464,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,571,34],"tags":[],"class_list":["post-64463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-in-evidenza","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/64463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=64463"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/64463\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/64464"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=64463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=64463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=64463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}