{"id":64598,"date":"2016-11-26T15:30:06","date_gmt":"2016-11-26T14:30:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/foto-e-video-corteo-per-angelo\/"},"modified":"2023-01-17T12:19:59","modified_gmt":"2023-01-17T11:19:59","slug":"123136-foto-e-video-corteo-per-angelo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/123136-foto-e-video-corteo-per-angelo\/","title":{"rendered":"FOTO e VIDEO &#8211; In centinaia in corteo per Angelo in una Sangineto blindata. Accesso al paese vietato"},"content":{"rendered":"<h4>Hanno invaso il Comune del Tirreno cosentino in ricordo del cane torturato ed ucciso chiedendo pene pi\u00f9 aspre per chi maltratta gli animali. I manifestanti sono stati accolti da decine di agenti antisommossa \u00a0e bloccati prima di arrivare a Sangineto paese: &#8220;la manifestazione non \u00e8 autorizzata&#8221;<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>SANGINETO (CS) &#8211; Numerosi bus sono approdati oggi a Sangineto per manifestare in ricordo di <strong>Angelo<\/strong>, il cane trucidato da quattro ragazzi del posto. I manifestanti per\u00f2 sono stati autorizzati a &#8216;sfilare&#8217; solo alla marina di Sangineto e non sono potuti salire in paese e sono stati <strong>bloccati a 6 km dal borgo<\/strong>. Per i resposabili delle forze dell&#8217;ordine la manifestazione era autorizzata solo a Sangineto Marina.<\/p>\n<p>Diversa invece, la versione dei promotori dell&#8217;iniziativa. L&#8217;obiettivo delle centinaia di persone arrivate\u00a0da tutta Italia,\u00a0era\u00a0quello di sensibilizzare le istituzioni affinch\u00e9 siano previste pene pi\u00f9 severe per chi maltratta e uccide animali.<\/p>\n<p>I manifestanti dopo aver urlato slogan, esposto striscioni,\u00a0<strong>hanno bloccato la statale 18 in segno di protesta<\/strong> e sono stati accolti <strong>da decine di agenti antissomossa e mezzi blindati della polizia<\/strong>.<\/p>\n<p>&#8220;Abbiamo trasmesso &#8211; scrive in una nota del Partito animalista europeo promotore della manifestazione insieme al Noita &#8211; una formale istanza alle prime tre cariche dello Stato ed ai relativi gruppi parlamentari. Fintanto che non verr\u00e0 modificata la Legge con l&#8217;inasprimento delle pene per i reati contro gli animali, nessun Angelo avr\u00e0 giustizia ed altri Angelo continueranno ad essere barbaramente trucidati per gioco o per noia con la consapevolezza di restare impuniti. A margine della manifestazione, viene lanciato il messaggio trasmesso dal Presidente del Senato in sostegno di questa iniziativa. <strong>La stampa locale riporta la forte preoccupazione nei cittadini di Sangineto tale da chiudere i negozi e le attivit\u00e0 commerciali e disertare le scuole per timore di gravi disordini&#8221;.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-123159 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/11\/sangineto-2-374x280.jpg\" alt=\"sangineto-2\" width=\"548\" height=\"410\" title=\"\"><\/p>\n<p>&#8220;La nostra condanna &#8211; continua il partito animalista europea &#8211; non \u00e8 indiscriminata, ma<strong> diretta esclusivamente ai quattro assassini ed a tutti coloro che li difendono avallando, minimizzando o giustificando il loro operato e non a coloro che ne hanno preso le distanze.<\/strong> La mobilitazione \u00e8 necessaria per mantenere elevata la tensione, altrimenti non se ne sarebbe pi\u00f9 parlato visto comunque che gli assassini sono stati non solo individuati ma anche denunciati e con i tempi biblici della nostra giustizia chiss\u00e0 tra quanti anni vedremo la sentenza, sempre se non interviene la prescrizione. Ma anche con il massimo della pena gli assassini non varcheranno mai la soglia del carcere. Al nostro fianco abbiamo i rappresentanti e la comunit\u00e0 di Sangineto per condannare senza mezzi termini ed in modo fermo l&#8217;efferato gesto dei quattro giovani&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-123161 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/11\/sangineto3-374x280.jpg\" alt=\"sangineto3\" width=\"498\" height=\"373\" title=\"\"><\/p>\n<p><span style=\"color: #ff0000;\"><strong>GUARDA IL VIDEO DEL CORTEO<\/strong><\/span><\/p>\n<p>[youtube url=&#8221;https:\/\/www.youtube.com\/watch?v=yJ8VYCEofM0&amp;feature=youtu.be&#8221; width=&#8221;500&#8243; height=&#8221;300&#8243;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-123160 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/11\/sangineto-4-399x280.jpg\" alt=\"sangineto-4\" width=\"399\" height=\"280\" title=\"\"><\/p>\n<p><span style=\"color: #ff0000;\"><strong>GUARDA IL VIDEO<\/strong><\/span><\/p>\n<p>[youtube url=&#8221;https:\/\/www.youtube.com\/watch?v=nHDkMnlfL50&amp;feature=youtu.be&#8221; width=&#8221;500&#8243; height=&#8221;300&#8243;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-123158 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/11\/sangineto-1-440x247.jpg\" alt=\"sangineto-1\" width=\"440\" height=\"247\" title=\"\"><\/p>\n<p><span style=\"color: #ff0000;\"><strong>VIDEO 01<\/strong><\/span><\/p>\n<p>[youtube url=&#8221;https:\/\/www.youtube.com\/watch?v=XTcevw-41Cg&amp;feature=youtu.be&#8221; width=&#8221;500&#8243; height=&#8221;300&#8243;]<\/p>\n<p><span style=\"color: #ff0000;\"><strong>VIDEO 02<\/strong><\/span><\/p>\n<p>[youtube url=&#8221;https:\/\/www.youtube.com\/watch?v=VWxn-7_LRSo&amp;feature=youtu.be&#8221; width=&#8221;500&#8243; height=&#8221;300&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hanno invaso il Comune del Tirreno cosentino in ricordo del cane torturato ed ucciso chiedendo pene pi\u00f9 aspre per chi maltratta gli animali. I manifestanti sono stati accolti da decine di agenti antisommossa \u00a0e bloccati prima di arrivare a Sangineto paese: &#8220;la manifestazione non \u00e8 autorizzata&#8221;<\/p>\n","protected":false},"author":22,"featured_media":64599,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-64598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/64598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=64598"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/64598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/64599"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=64598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=64598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=64598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}