{"id":64604,"date":"2016-11-26T17:08:21","date_gmt":"2016-11-26T16:08:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/spaccio-sostanze-stupefacenti-assolto-imprenditore-del-cosentino\/"},"modified":"2023-01-17T12:20:00","modified_gmt":"2023-01-17T11:20:00","slug":"123190-spaccio-sostanze-stupefacenti-assolto-imprenditore-del-cosentino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/123190-spaccio-sostanze-stupefacenti-assolto-imprenditore-del-cosentino\/","title":{"rendered":"Spaccio di cocaina in provincia di Cosenza, assolto imprenditore"},"content":{"rendered":"<h4>L\u2019uomo era stato arrestato a seguito di una &#8216;soffiata&#8217; fatta da una fonte confidenziale dei carabinieri.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Imprenditore assolto \u201cper non aver commesso il fatto\u201d. \u00c8 l&#8217;esito della sentenza a cui sono giunti i giudici del Tribunale di Castrovillari a favore di A.D.M., quarantaquattrenne di Mirto Crosia accusato di spaccio di sostanza stupefacente difeso dall\u2019avvocato Francesco Nicoletti.\u00a0L\u2019uomo era stato tratto in arresto lo scorso mese di giugno all\u2019esito di una perquisizione effettuata congiuntamente dai Carabinieri della Stazione di Calopezzati e dai Carabinieri della Stazione di Mirto-Crosia. In quell\u2019occasione i militari hanno rinvenuto della cocaina, un bilancino di precisione e un coltello con la lama annerita utile per il confezionamento delle dosi dopo aver setacciato l\u2019abitazione estiva di Fiumarella, l&#8217;azienda di propriet\u00e0 dell&#8217;imputato e la propria auto.\u00a0<strong>L\u2019attivit\u00e0 di indagine prende il via in seguito alla ricezione da parte dei carabinieri della notizia riferita da una fonte confidenziale, secondo la quale nei luoghi di propriet\u00e0 o comunque nella disponibilit\u00e0 dell\u2019imprenditore si trovava la sostanza stupefacente.<\/strong> La perquisizione \u00e8 stata effettuata dai militari con l\u2019utilizzo del cane antidroga \u201cSambo\u201d e nl corso dell&#8217;operazione sono stati rinvenuti proiettili vari nonch\u00e9 numerose carte di identit\u00e0 di provenienza illecita in quanto oggetto di regolare denuncia di smarrimento effettuata dai legittimi proprietari. Scattate le manette, l\u2019imprenditore \u00e8 comparso, in stato di arresto, dinanzi al Tribunale penale di Castrovillari per essere giudicato con il rito direttissimo. In tale sede la difesa ha chiesto e ottenuto la definizione del processo nelle forme del rito abbreviato, all\u2019esito del quale, in accoglimento delle tesi e delle richieste avanzate dall\u2019avvocato Francesco Nicoletti, il Tribunale ha emesso una sentenza di assoluzione nei confronti del quarantaquattrenne A.D.M con la formula \u201cper non aver commesso il fatto\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019uomo era stato arrestato a seguito di una &#8216;soffiata&#8217; fatta da una fonte confidenziale dei carabinieri.<\/p>\n","protected":false},"author":22,"featured_media":64605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-64604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/64604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=64604"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/64604\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/64605"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=64604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=64604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=64604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}