{"id":64900,"date":"2016-12-03T12:44:58","date_gmt":"2016-12-03T11:44:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/imprenditore-vittima-di-usura-segregato-e-seviziato-perche-non-restituisce-prestito\/"},"modified":"2023-01-17T12:20:37","modified_gmt":"2023-01-17T11:20:37","slug":"124538-imprenditore-vittima-di-usura-segregato-e-seviziato-perche-non-restituisce-prestito","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/124538-imprenditore-vittima-di-usura-segregato-e-seviziato-perche-non-restituisce-prestito\/","title":{"rendered":"Imprenditore vittima di usura segregato in un bar e seviziato per giorni"},"content":{"rendered":"<h4>A spingerlo tra le grinfie dei &#8216;cravattari&#8217; facendosi prestare del denaro sarebbe stata l&#8217;ex fidanzata di origini ucraine.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; Sequestrato e picchiato per quattro giorni\u00a0perch\u00e8 non riesce a pagare le rate di un prestito di circa duemila euro. Il terribile episodio \u00e8 accaduto a Nettuno in provincia di Roma dove i carabinieri hanno eseguito cinque misure cautelari. Tra i destinatari del provvedimento appare anche l\u2019ex compagna\u00a0della vittima, di origine ucraina, con la quale aveva avuto un figlio.Sarebbe stata proprio lei ad indicare alla vittima, un imprenditore di 42 anni, di rivolgersi agli usurai. Il\u00a0debito richiesto non ammonterebbe ad una grossa cifra, ma sarebbe lievitato a causa degli interessi chiesti dagli usurai.\u00a0<strong>Quando l&#8217;uomo non \u00e8 pi\u00f9 riuscito a pagare, gli usurai lo hanno sequestrato e rinchiuso in uno scantinato di un bar a Nettuno, aiutati dalla loro complice, l&#8217;ex convivente della vittima.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Quattro lunghi giorni da incubo, il 42enne \u00e8 stato picchiato ogni giorno da due della banda e costretto a subire pesanti umiliazioni anche da parte dell&#8217;ucraina. Al quinto giorno gli strozzini lo hanno accompagnato a un appuntamento con un conoscente, che avrebbe dovuto prestargli il denaro. Ma una volta sul posto i due carcerieri, ormai pronti a intascare i soldi, hanno commesso un errore: si sono distratti e la vittima ne ha approfittato per fuggire. E poi ha chiesto aiuto al 112.\u00a0I Carabinieri della Compagnia di Anzio, dopo una attenta indagine, hanno eseguito un&#8217;ordinanza applicativa di misure cautelari nei confronti della banda Nettuno, ritenuta responsabile di aver &#8220;<strong>sequestrato e seviziato<\/strong>&#8221; la loro vittima.\u00a0Per C.A., 35 anni, \u00e8 scattata la custodia in carcere, mentre il fratello M.A., 22 anni, e G.B., 40 anni, sono finiti ai domiciliari. I tre sono accusati di estorsione, usura, sequestro di persona e lesioni. Invece per P.B., 18 anni, e <strong>per L.K., ex convivente della vittima, di origine ucraina, il giudice ha disposto l\u2019obbligo di dimora nel Comune di Nettuno (dove tutti e cinque sono residenti): a loro due \u00e8 contestato un solo reato, quello di lesioni.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A spingerlo tra le grinfie dei &#8216;cravattari&#8217; facendosi prestare del denaro sarebbe stata l&#8217;ex fidanzata di origini ucraine.<\/p>\n","protected":false},"author":22,"featured_media":64901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,16],"tags":[],"class_list":["post-64900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/64900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=64900"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/64900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/64901"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=64900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=64900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=64900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}