{"id":64949,"date":"2016-12-05T11:45:23","date_gmt":"2016-12-05T10:45:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/canile-di-mortara-gruppo-ecologista-la-foresta-che-avanza-tante-denunce-e-poca-chiarezza\/"},"modified":"2023-01-17T12:20:43","modified_gmt":"2023-01-17T11:20:43","slug":"124844-canile-di-mortara-gruppo-ecologista-la-foresta-che-avanza-tante-denunce-e-poca-chiarezza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/124844-canile-di-mortara-gruppo-ecologista-la-foresta-che-avanza-tante-denunce-e-poca-chiarezza\/","title":{"rendered":"Canile di Mortara, gruppo ecologista &#8216;La Foresta che Avanza&#8217;: &#8220;tante denunce e poca chiarezza&#8221;"},"content":{"rendered":"<p><strong>Si chiedono le dimissioni della dottoressa Putort\u00ec ma soprattutto che il Comune di Mortara (Rc) trovi una soluzione concreta.<\/strong><!--more--><\/p>\n<p>MORTARA (RC) &#8211; \u201cIn merito alla <strong>sorte dei cani ospiti del canile comunale di Mortara<\/strong> esigiamo, una volta per tutte, <strong>chiarezza<\/strong>. Sono mesi che monitoriamo questa <strong>assurda vicenda<\/strong> ed ora i nostri <strong>sospetti<\/strong> e le nostre denunce hanno trovato conferma: gli animali del canile in questione dovranno essere spostati in altre strutture ricettive, nello specifico non viene comunicato quali, per un periodo di tempo non precisato, per poter finire i lavori di manutenzione interni al canile stesso\u201d.<\/p>\n<p>Sono queste le dure dichiarazioni di Roberta Riso, responsabile regionale de<strong> La Foresta che Avanza,<\/strong> Gruppo ecologista nato in seno al movimento CasaPound Italia.<\/p>\n<p>\u201cNei mesi di Aprile e Maggio &#8211; spiega &#8211; abbiamo prestato opera di volontariato con altri ragazzi e ragazze all\u2019interno del canile in questione e le anomalie erano pi\u00f9 che evidenti. A seguito di ci\u00f2 abbiamo denunciato pi\u00f9 volte suddette inadeguatezze senza, per\u00f2, ottenere alcuna risposta. Adesso apprendiamo che gli animali ospiti del canile di Mortara saranno spostati in altre strutture&#8221;.<\/p>\n<p>&#8220;In virt\u00f9 di ci\u00f2, ci chiediamo &#8211; incalza &#8211; per quale motivo l\u2019amministrazione comunale si sia resa conto solo ora di aver assegnato e consegnato all\u2019associazione Aratea (vincitrice del bando), un canile incompleto e inadatto alla permanenza dei cani randagi della citt\u00e0. Questa situazione \u00e8 la conferma di tutte le denunce effettuate nei mesi passati e dell\u2019inadeguatezza di coloro che gestiscono il canile (palesata anche dalla pubblicizzazione dei corsi di formazione seguiti dal personale interno tramite slide lette e commentate da consiglieri comunali che non sappiamo a quale titolo fossero saliti in cattedra)\u201d.<\/p>\n<p>\u201cTutto ci\u00f2 &#8211; prosegue Riso &#8211; \u00e8 riprovevole ed \u00e8 la dimostrazione tangibile di come quella Falcomat\u00e0 sia un&#8217;amministrazione poco credibile. Questa volta non ci accontenteremo delle solite sterili ed inutili promesse ma pretendiamo risposte e soluzioni concrete. Non possiamo permettere che, dopo le morti per cimurro e le altre morti sospette, le sorti di questi cani siano ancora in bilico e a forte rischio; non permetteremo che questo scempio prosegua. In virt\u00f9 di ci\u00f2 &#8211; conclude &#8211; chiediamo le dimissioni della dottoressa Putort\u00ec, responsabile del canile, in modo tale che venga affidato ad associazioni pi\u00f9 capaci e competenti. Quello delle dimissioni sar\u00e0 un atto di responsabilit\u00e0 da parte della stessa\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si chiedono le dimissioni della dottoressa Putort\u00ec ma soprattutto che il Comune di Mortara (Rc) trovi una soluzione concreta.<\/p>\n","protected":false},"author":21,"featured_media":64950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-64949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/64949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=64949"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/64949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/64950"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=64949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=64949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=64949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}