{"id":6497,"date":"2012-10-25T06:37:37","date_gmt":"2012-10-25T04:37:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=6497"},"modified":"2023-01-17T13:39:45","modified_gmt":"2023-01-17T12:39:45","slug":"2589-al-teatro-dellacquario-i-edizione-di-salome","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2589-al-teatro-dellacquario-i-edizione-di-salome\/","title":{"rendered":"Al Teatro dell&#8217;Acquario I^ edizione di Salom\u00e8"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 9pt; line-height: 115%; font-family: Arial, sans-serif; background-color: white;\"><strong>COSENZA<\/strong> &#8211; Dal 25 al 27 ottobre 2012 il Teatro dell\u2019Acquario di Cosenza tiene a battesimo la prima edizione di Salom\u00e8, Festival di monologhi al femminile, prodotto<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 9pt; line-height: 115%; font-family: Arial, sans-serif; background-color: white;\"> dall\u2019 Associazione Culturale\/Compagnia Le Sei Sorelle e dal Centro Rat \/ Teatro dell\u2019Acquario. In programma 10 monologhi per 10 autrici ed autori teatrali, protagoniste assolute le donne. Inaugurano la rassegna gioved\u00ec 25 ottobre Freak and Frog, di e con Stefania De Cola e Salvatore Vercellino, Io, Maria, letture sparse dai lavori di Maria<\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Dal 25 al 27 ottobre 2012 il Teatro dell\u2019Acquario di Cosenza tiene a battesimo la prima edizione di Salom\u00e8, Festival di monologhi al femminile, prodotto<\/p>\n","protected":false},"author":22,"featured_media":6498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-6497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=6497"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6497\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/6498"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=6497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=6497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=6497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}