{"id":65059,"date":"2016-12-07T23:04:11","date_gmt":"2016-12-07T22:04:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/due-giorni-comicita-cosenza-vincenzo-salemme\/"},"modified":"2023-01-17T12:20:56","modified_gmt":"2023-01-17T11:20:56","slug":"125397-due-giorni-comicita-cosenza-vincenzo-salemme","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/125397-due-giorni-comicita-cosenza-vincenzo-salemme\/","title":{"rendered":"Due giorni di comicit\u00e0 a Cosenza con Vincenzo Salemme"},"content":{"rendered":"<h4>Doppio appuntamento, il 9 e il 10 dicembre, nel cuore del centro storico sul palco del Teatro Rendano.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211;\u00a0Torna al Teatro Rendano l&#8217;irresistibile comicit\u00e0 di Vincenzo Salemme. Il cartellone firmato L&#8217;AltroTeatro propone un altro asso, venerd\u00ec 9 e sabato 10 dicembre, alle ore 20.30, la commedia \u201cUna festa esagerata\u201d scritta, diretta e interpretata dal comico partenopeo. Evento patrocinato dall\u2019amministrazione comunale di Cosenza e organizzato da un gruppo di operatori del mondo dello spettacolo locale: Enzo Noce, Giuseppe Citrigno e Gianluigi Fabiano. Sul palco del Teatro Rendano 14 appuntamenti all\u2019insegna del divertimento e del puro spettacolo. Prosa, commedie e tanta musica questi gli ingredienti del cartellone ideato da \u201cL\u2019AltroTeatro\u201d. In realt\u00e0, da diverse settimane \u00e8 stato annunciato il tutto esaurito per la commedia campioni d&#8217;incassi. Un nuovo testo divertentissimo, al centro: <strong>una famiglia borghese di oggi, composta da padre, madre e figlia coinvolta nell\u2019organizzazione del debutto in societ\u00e0 della giovane Mirea.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Ed ovviamente, non potrebbe esserci nulla di pi\u00f9 semplice se non fosse che il padre (Vincenzo Salemme), uomo di valori morali deve confrontarsi con una moglie \u201caffamata\u201d di popolarit\u00e0 e di scalata sociale, disposta a tutto pur di incassare soldi e fare la vita da \u201cborghese milanese\u201d scendendo a compromessi con la politica locale. <strong>\u201cUna festa esagerata\u201d scritto, diretto e interpretato dallo stesso Salemme \u00e8 una commedia dall\u2019umorismo acuto.<\/strong> \u201cNasce da un\u2019idea che avevo in mente da tempo, uno spunto che mi permettesse di raccontare in chiave realistica e divertente il lato oscuro e grottesco dell\u2019animo umano \u2013 scrive nelle sue note di regia Salemme -.<\/p>\n<p>&nbsp;<\/p>\n<p>Non dell\u2019umanit\u00e0 intera ovviamente, ma di quella grande melassa\/massa dalla quale provengo, quel blocco sociale che in Italia viene definito \u201cpiccola borghesia\u201d. Volevo parlare delle cosiddette persone normali, di coloro che vivono nascondendosi dietro lo scudo delle convenzioni, coloro che vivono le relazioni sociali usando il codice dell\u2019ipocrisia come unica strada per la sopravvivenza. Sopravvivenza alle \u201cchiacchiere\u201d, alle \u201cvoci\u201d, ai sussurri pettegoli e sospettosi dei vicini. E s\u00ec, perch\u00e9 io vedo la nostra enorme piccola borghesia come un grande condominio, fatto di vicini che si prestano lo zucchero, il termometro e <strong>si scambiano i saluti ma che, al contempo, sono pronti a tradirsi, abbandonarsi e, in qualche caso estremo, anche a condannarsi a vicenda\u201d.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Doppio appuntamento, il 9 e il 10 dicembre, nel cuore del centro storico sul palco del Teatro Rendano.<\/p>\n","protected":false},"author":22,"featured_media":65060,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,571,34],"tags":[],"class_list":["post-65059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-in-evidenza","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/65059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=65059"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/65059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/65060"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=65059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=65059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=65059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}