{"id":65258,"date":"2016-12-12T20:06:08","date_gmt":"2016-12-12T19:06:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/navi-veleni-deputati-m5s-chiarire-cause-morte-de-grazia\/"},"modified":"2023-01-17T12:21:28","modified_gmt":"2023-01-17T11:21:28","slug":"126185-navi-veleni-deputati-m5s-chiarire-cause-morte-de-grazia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/126185-navi-veleni-deputati-m5s-chiarire-cause-morte-de-grazia\/","title":{"rendered":"Navi dei Veleni e radioattivit\u00e0, ancora mistero a ventuno anni dalla morte di De Grazia"},"content":{"rendered":"<h4>Non sono mai state chiarite le circostanze che portarono al decesso del capitano che indagava sulle navi dei veleni.<\/h4>\n<p><!--more--><br \/>\nCATANZARO\u00a0&#8211; &#8220;Oggi ricorre il 21\u00b0 avversario della morte del capitano Natale De Grazia, scomparso mentre indagava sul traffico illecito di rifiuti radioattivi ed il fenomeno delle navi a perdere&#8221;. Lo affermano i deputati della Commissione Ambiente del M5S e il portavoce di Catanzaro del M5S Paolo Parentela. Le indagini del pool investigativo coordinato dal procuratore Francesco Neri, \u00e8 scritto nella nota, &#8220;subirono un duro colpo con la morte di De Grazia e rappresentano, ancora oggi, uno dei pi\u00f9 fitti misteri della storia d&#8217;Italia&#8221;. &#8220;Bisogna chiarire ancora &#8211; afferma Parentela &#8211; tutte le circostanze della morte e i mandanti della morte. Non vogliamo che il sacrificio di De Grazia rimanga vano, pretendiamo che la politica, ad oltre 20 anni di distanza, si impegni veramente per risolvere questo mistero e restituire giustizia ai cittadini italiani che vogliono la verit\u00e0. La politica deve impegnarsi per indagare a fondo sulle navi dei veleni, perch\u00e9 la tecnologia moderna consente di scoprire la verit\u00e0 sul contenuto di quelle navi e sul traffico internazionale di rifiuti&#8221;. &#8220;La memoria di De Grazia &#8211; affermano i deputati cinque stelle &#8211; va rispettata anche attraverso la<strong> desecretazione dei documenti che ancora giacciono negli uffici del Parlamento. Non si pu\u00f2 continuare a nascondere ancora la verit\u00e0<\/strong>, lo si deve alla memoria di De Grazia e a tutti quei cittadini che continuano a morire in silenzio, magari per colpa di quelle navi affondate a largo di quelle spiagge in cui pescano o fanno il bagno&#8221;. &#8220;Noi &#8211; conclude Parentela &#8211; non ci arrenderemo mai. Lo facciamo anche per rendere il giusto omaggio al suo sacrificio ed al suo coraggio&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non sono mai state chiarite le circostanze che portarono al decesso del capitano che indagava sulle navi dei veleni.<\/p>\n","protected":false},"author":22,"featured_media":65259,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-65258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/65258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=65258"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/65258\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/65259"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=65258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=65258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=65258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}