{"id":6535,"date":"2012-10-25T11:36:21","date_gmt":"2012-10-25T09:36:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=6535"},"modified":"2023-01-17T13:39:47","modified_gmt":"2023-01-17T12:39:47","slug":"2610-sindacati-contestano-la-riorganizzazione-del-personale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2610-sindacati-contestano-la-riorganizzazione-del-personale\/","title":{"rendered":"Unical: Sindacati contestano la riorganizzazione del personale"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #383838; font-family: Arial, 'Times New Roman', serif; font-size: 12px; line-height: normal; background-color: #ffffff;\">(ASCA) &#8211; <strong>RENDE<\/strong> &#8211; I sindacati Cgil, Cisl, Uil, operanti nellUniversita&#8217; della Calabria, a seguito dell&#8217;incontro con il Direttore Generale, tenutosi lunedi&#8217; 22 ottobre, &#8221;manifestano forte<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #383838; font-family: Arial, 'Times New Roman', serif; font-size: 12px; line-height: normal; background-color: #ffffff;\"> disappunto per quanto illustrato riguardo la riorganizzazione del personale.<\/span><br style=\"margin: 0px; padding: 0px; color: #383838; font-family: Arial, 'Times New Roman', serif; line-height: normal; background-color: #ffffff;\" \/><span style=\"background-color: #ffffff; color: #383838; font-family: Arial, 'Times New Roman', serif; font-size: 12px; line-height: normal;\">Contestano, preliminarmente, l&#8217;assenza di un profondo processo di revisione di tutte le strutture dell&#8217;Ateneo, con particolare riguardo alle politiche di gestione delle risorse umane, finanziarie e strumentali. Tale processo avrebbe dovuto consentire all&#8217;Unical l&#8217;adeguamento alle reali esigenze organizzative per fronteggiare le evidenti criticita&#8217;, in ordine alla riduzione dei finanziamenti pubblici ed al limitatissimo turn over&#8221;.<\/span><br \/><span style=\"background-color: #ffffff; color: #383838; font-family: Arial, 'Times New Roman', serif; font-size: 12px; line-height: normal;\">&#8221;Una riorganizzazione, non solo limitata alle singole strutture dipartimentali ma addirittura priva di criteri oggettivi, non calibrata su un progetto culturale e scientifico, di cui dovrebbero essersi dotate le varie strutture, non puo&#8217; che denunciare la miopia di questa Amministrazione&#8221;.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(ASCA) &#8211; RENDE &#8211; I sindacati Cgil, Cisl, Uil, operanti nellUniversita&#8217; della Calabria, a seguito dell&#8217;incontro con il Direttore Generale, tenutosi lunedi&#8217; 22 ottobre, &#8221;manifestano forte<\/p>\n","protected":false},"author":22,"featured_media":6536,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,5,44],"tags":[],"class_list":["post-6535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-old","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=6535"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6535\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/6536"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=6535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=6535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=6535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}