{"id":65600,"date":"2016-12-20T14:55:19","date_gmt":"2016-12-20T13:55:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/p-zza-fera-presentata-interrogazione-parlamentare-perche-occhiuto-non-rilascia-le-carte-del-collaudo\/"},"modified":"2023-01-17T12:22:07","modified_gmt":"2023-01-17T11:22:07","slug":"127611-p-zza-fera-presentata-interrogazione-parlamentare-perche-occhiuto-non-rilascia-le-carte-del-collaudo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/127611-p-zza-fera-presentata-interrogazione-parlamentare-perche-occhiuto-non-rilascia-le-carte-del-collaudo\/","title":{"rendered":"P.zza Fera, presentata interrogazione parlamentare: &#8220;Perch\u00e8 Occhiuto non rilascia le carte del collaudo?&#8221;"},"content":{"rendered":"<p class=\"p1\"><strong>Il M5S ha presentato un&#8217;interrogazione parlamentare, primo firmatario Morra, per far chiarezza circa la sicurezza della piazza appena inaugurata<\/strong><!--more--><\/p>\n<p class=\"p1\">COSENZA &#8211; Il Movimento 5 Stelle ha presentato un&#8217;interrogazione parlamentare, prima firma <strong>Nicola Morra<\/strong>, al ministro delle Infrastrutture e dei Trasporti nell&#8217;intento di fare chiarezza e rassicurare i cittadini circa la <strong>sicurezza di piazza Fera che \u00e8 stata aperta ai cosentini pur non essendo ultimata l&#8217;intera opera.<\/strong> In particolare si chiedono delucidazioni in merito al certificato di collaudo statico dell&#8217;intero edificio, il motivo del persistente ritardo nel compimento contrattuale dell&#8217;opera e se siano state o saranno applicate penali per l&#8217;<strong>abnorme ritardo (ad oggi siamo oltre i 555 gg.<\/strong>). Vogliamo sottolineare, inoltre, che tutte queste polemiche si sarebbero potute evitare se il sindaco avesse adottato realmente la tanto sbandierata trasparenza, pubblicando sul sito del comune tutta la documentazione dovuta. <strong>Perch\u00e8 Mario Occhiuto non tranquillizza la citt\u00e0? Invece di rilasciare dichiarazioni ai giornali perch\u00e8 non fornisce l&#8217;incartamento inerente al collaudo di Piazza Fera?<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il M5S ha presentato un&#8217;interrogazione parlamentare, primo firmatario Morra, per far chiarezza circa la sicurezza della piazza appena inaugurata<\/p>\n","protected":false},"author":21,"featured_media":65601,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-65600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/65600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=65600"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/65600\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/65601"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=65600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=65600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=65600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}