{"id":65759,"date":"2016-12-23T16:49:52","date_gmt":"2016-12-23T15:49:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-un-pulmino-nuovo-di-zecca-per-i-diversamente-abili\/"},"modified":"2023-01-17T12:22:25","modified_gmt":"2023-01-17T11:22:25","slug":"128335-cosenza-un-pulmino-nuovo-di-zecca-per-i-diversamente-abili","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/128335-cosenza-un-pulmino-nuovo-di-zecca-per-i-diversamente-abili\/","title":{"rendered":"Cosenza, un pulmino nuovo di zecca per i diversamente abili (VIDEO)"},"content":{"rendered":"<p><strong>Padre Fedele: &#8220;promessa mantenuta, ecco il primo pulmino per i diversamente abili cosentini&#8221;<\/strong><!--more--><\/p>\n<p>COSENZA &#8211;<strong> Porta il logo della sua associazione di solidariet\u00e0 sociale, il \u201cParadiso di poveri\u201d. Ed era fiero, Padre Fedele, di poterlo presentare alla citt\u00e0, questa mattina, in piazza XI Settembre.<\/strong> C&#8217;erano anche tanti bambini, che hanno cantato le melodie natalizie, in un bel clima di festa. La gente era indaffarata negli ultimi acquisti, ma in molti si sono fermati e hanno applaudito il religioso e supertifoso, che aveva anche ricoperto il mezzo con una grande bandiera rossobl\u00f9.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-128338\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/12\/20161223_115524-440x247.jpg\" alt=\"\" width=\"440\" height=\"247\" title=\"\"><br \/>\n<strong>Dopo la preghiera di rito e la benedizione, il pulmino, acquistato con i soldi raccolti per strada da Padre Fedele, offerti da tanti cosentini, e grazie anche allo sconto di un concessionario, il pulmino \u00e8 stato \u201cscoperto\u201d. Dopo le feste ne arriver\u00e0 un altro, questa volta pagato interamente da una nota gioielleria cosentina.<\/strong> Il vulcanico frate, infatti, riesce come nessun altro a calamitare le simpatie e le attenzioni di tanti imprenditori e a canalizzare le loro energie verso la solidariet\u00e0. Prima di andar via, ha lanciato ancora il suo appello alla Chiesa: \u201cfatemi dire messa \u2013 ha detto Padre Fedele \u2013 \u00e8 la cosa che voglio di pi\u00f9 al mondo, perch\u00e8 io sono un sacerdote e ora sapete che non ho colpe\u201d.<\/p>\n<p><iframe loading=\"lazy\" title=\"Padre Fedele presentazione pulmino disabili\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/K6646hE0myo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Padre Fedele: &#8220;promessa mantenuta, ecco il primo pulmino per i diversamente abili cosentini&#8221;<\/p>\n","protected":false},"author":32,"featured_media":65760,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,571],"tags":[],"class_list":["post-65759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/65759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=65759"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/65759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/65760"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=65759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=65759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=65759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}