{"id":65767,"date":"2016-12-25T07:09:27","date_gmt":"2016-12-25T06:09:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/128365\/"},"modified":"2023-01-17T12:22:26","modified_gmt":"2023-01-17T11:22:26","slug":"128365-128365","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/128365-128365\/","title":{"rendered":"XV rassegna di Teatro e Musica &#8216;Primafila&#8217;"},"content":{"rendered":"<p><strong>Arriva il Festival della Comicit\u00e0 con Teo Teocoli, Phino, Magico Alverini e Paradiso.<\/strong><br \/>\n<!--more--><\/p>\n<p>CASTROVILLARI (CS) &#8211;\u00a0Dopo l\u2019apertura scoppiettante con due grandi attori comici, Dado a Cassano e Vergassola a Mormanno, pausa natalizia per \u201c Primafila\u201dla rassegna organizzata dall\u2019Associazione Culturale Novecento Teatri. L\u2019evento torner\u00e0 sul palcoscenico, questa volta del Sybaris, con la XV^ Edizione del Festival della Comicit\u00e0. Un appuntamento fisso nel giorno di Santo Stefano, per tutti gli appassionati della comicit\u00e0.<br \/>\nIn scena Gianfranco Phino, Dino Paradiso, Alberto Magico Alivernini.<\/p>\n<p><strong>Gianfranco Phino<\/strong> \u00e8 sicuramente uno dei pi\u00f9 completi. Dopo il grande successo di pubblico e critica con la sua performance ad Italia&#8217;s Got Talent, torna a calcare le tavole del palcoscenico con lo spettacolo &#8220;Phino a che ce n&#8217;ho!&#8221;, uno show tutto da ridere e che racconta l&#8217;artista, l&#8217;uomo e il poeta Gianfranco.<br \/>\n<strong>Alberto Magico Alivernini<\/strong> ci allieter\u00e0 con uno spettacolo misto tra comicit\u00e0 e magia senza mai capire dove finisca il mago e dove cominci il comico. Tra le sue esperienze professionali vanno ricordate: le partecipazioni ai salotti televisivi del&#8221;Maurizio Costanzo Show&#8221;, &#8220;Tappeto Volante&#8221;, &#8220;Domenica in&#8221; e a quello del Bagaglino di Pier Francesco Pingitore.<br \/>\n<strong>Dino Paradiso<\/strong>, la sua formazione \u00e8 avvenuta &#8220;sul campo&#8221;, cio\u00e8 per strada. Il suo cabaret \u00e8 infatti frutto dello studio dei personaggi che si incontrano quotidianamente sotto casa,al mercato, al bar. Perfeziona lo studio del teatro comico frequentando la scuola di teatro comico &#8220;Comic Lab&#8221;, diretta dalla grande Serena Dandini.. Vincitore del premio \u201cbravograzie 2013\u201d e comico dal 2015 del cast di Colorado.<\/p>\n<p>Grande attesa anche per il 27 dicembre; sar\u00e0 di scena sempre a Castrovillari presso il Teatro Sybaris, il grande <strong>Teo<\/strong> <strong>Teocoli .<\/strong> Il nuovo show \u00e8 un susseguirsi di monologhi, parti musicali alternate alle imitazioni pi\u00f9 ridicole e alle parodie pi\u00f9 celebri che hanno reso popolare l\u2019artista al grande pubblico. In una parola, uno show dove si ride molto!!&#8230;<\/p>\n<p>L\u2019evento gode del contributo della Regione Calabria, del Parco del Pollino, dei Comuni di Castrovillari, Cassano J. Morano C. e Mormanno, ma anche di Nocara, Acquaformosa e Santa Domenica Talao dal momento che la rassegna \u00e8 partita gi\u00e0 l\u2019estate scorsa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arriva il Festival della Comicit\u00e0 con Teo Teocoli, Phino, Magico Alverini e Paradiso.<\/p>\n","protected":false},"author":20,"featured_media":65768,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,34],"tags":[],"class_list":["post-65767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/65767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=65767"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/65767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/65768"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=65767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=65767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=65767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}