{"id":65936,"date":"2016-12-29T08:31:11","date_gmt":"2016-12-29T07:31:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tarantella-power-si-danza-al-ritmo-del-canzoniere-salentino\/"},"modified":"2023-01-17T12:22:45","modified_gmt":"2023-01-17T11:22:45","slug":"129048-tarantella-power-si-danza-al-ritmo-del-canzoniere-salentino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/129048-tarantella-power-si-danza-al-ritmo-del-canzoniere-salentino\/","title":{"rendered":"&#8216;Tarantella Power&#8217;, si danza al ritmo del Canzoniere Salentino"},"content":{"rendered":"<p><strong>Stasera gran finale del festival con Michele Placido \u201cSulle orme di Annibale\u201d<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>TIRIOLO (CZ) &#8211; L\u2019inclemenza del tempo non ha fermato la voglia di suonare e di danzare che finora ha regnato sovrana al \u201cTarantella Power\u201d. Nonostante le avverse condizioni meteorologiche infatti anche la terza giornata del festival ha registrato una buona partecipazione di pubblico, grazie al richiamo del <strong>\u201cCanzoniere Grecanico Salentino\u201d<\/strong>, il pi\u00f9 importante gruppo di musica popolare pugliese. Un richiamo che il \u201cCanzoniere\u201d ha ripagato ampiamente con un\u2019esibizione straordinaria al teatro tenda allestito nell\u2019area archeologica Gianmartino, esibizione nel segno della originalit\u00e0 del gruppo fondata sull\u2019affascinante dicotomia tra tradizione e modernit\u00e0, cio\u00e8 sulla reinterpretazione in chiave moderna delle tradizioni che ruotano attorno alla celebre \u201cpizzica tarantata\u201d rituale. Com\u2019era ampiamente nelle previsioni della vigilia, il concerto del \u201cCanzoniere Grecanico Salentino\u201d si \u00e8 ben presto trasformato in un\u2019esplosione di energia, passione, ritmo e magia, che ha trascinato i presenti in vorticose danze sul battito del tamburello, cuore pulsante della tradizione salentina. Grazie al \u201cCanzoniere\u201d \u201cTarantella Power\u201d ha rinverdito anche il suo glorioso passato, al punto che uno dei componenti del gruppo salentino, Mauro Durante, ha ricordato le trascorse partecipazioni al festival calabrese del padre Daniele, dal quale ha ereditato la leadership del \u201cCanzoniere\u201d. Per gli organizzatori del \u201cTarantella Power\u201d \u2013 l\u2019Ats Comune di Tiriolo e l\u2019associazione Arpa\u201d &#8211; dunque un ulteriore motivo di soddisfazione, che rafforza la consapevolezza del successo della manifestazion\u00ece. Il cartellone odierno comunque prevede anche altri appuntamenti imperdibili: si parte dalle ore 17 con l\u2019animazione per le strade del centro e delle frazioni di Tiriolo con<strong> \u201cBanda Pilusa\u201d<\/strong>, mentre si chiuderanno i corsi organizzati nell\u2019ambito del festival per tramandare la ricchezza artistica e culturale della Calabria: corsi sulla danza tradizionale calabrese, canto, organetto, tamburello, zampogna, lira calabrese (con i docenti Francesca Trenta, Antonio Critelli, Salvatore Megna, Danilo Gatto, Giuseppe Stilo, Fortunato Verduci e Antonio Ranieri) e infine il corso di tessitura a mano su telaio a due e quattro licci presso la <strong>bottega artigiana Tessilart<\/strong> di Tiriolo (con la docente Mirella Leone).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-129050 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2016\/12\/DSCN5217-534x400.jpg\" alt=\"dscn5217\" width=\"534\" height=\"400\" title=\"\"><\/p>\n<p>Al solito, il \u201ccuore\u201d del \u201cTarantella Power\u201d saranno l\u2019Antiquarium e il parco archeologico di Gianmartino: oggi, per quanti l\u2019hanno finora persa, ci sar\u00e0 l\u2019ultima possibilit\u00e0 di assistere al restauro &#8211; \u201cin diretta\u201d \u2013 di 23 monete e due statuette ritrovate nella campagna di scavi 2014-2015, affidato alla restauratrice Aba Muleo e all\u2019archeologa Paola Caruso nel contesto dell\u2019iniziativa \u201cCantiere aperto: comunicare la conservazione\u201d (nato dalla collaborazione con Mibac\/Soprintendenza archeologica Belle arti e Paesaggio), e di partecipare alle visite guidate al museo e all\u2019area archeologica, che contiene reperti di grande valore culturale. Infine, al teatro tenda il gran finale (ingresso 4 euro): l\u2019evento speciale Michele Placido\/Phaleg <strong>\u201cSulle orme di Annibale\u201d<\/strong>, spettacolo teatro e musica su testo di <strong>Paolo Rumiz<\/strong> (un viaggio contemporaneo sulle orme di quello che Annibale fece duemila anni fa, con suggestivi paragoni tra passato e presente) e, a seguire, <strong>Frankie hi-nrg<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stasera gran finale del festival con Michele Placido \u201cSulle orme di Annibale\u201d<\/p>\n","protected":false},"author":20,"featured_media":65937,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,34],"tags":[],"class_list":["post-65936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/65936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=65936"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/65936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/65937"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=65936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=65936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=65936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}