{"id":6751,"date":"2012-10-29T14:03:23","date_gmt":"2012-10-29T13:03:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=6751"},"modified":"2023-01-17T13:39:59","modified_gmt":"2023-01-17T12:39:59","slug":"2724-guendalina-canessa-frequenta-mimmo-gravina","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2724-guendalina-canessa-frequenta-mimmo-gravina\/","title":{"rendered":"Guendalina Canessa frequenta Mimmo Gravina"},"content":{"rendered":"<p><span style=\"color: #333333; font-family: 'Segoe UI', Calibri, 'Myriad Pro', Myriad, 'Trebuchet MS', Helvetica, Arial, sans-serif; font-size: 14px; line-height: 21px; text-align: justify; background-color: #ffffff;\">Guendalina Canessa dichiara di avere un nuovo flirt da circa due mesi. Tempo fa \u00e8 stata paparazzata con Fabio Borriello, fratello di Marco. Pare che questa sia stata una svista e che il ragazzo in questione fosse Mimmo Gravina, imprenditore napoletano, ex fidanzato di Francesca Fioretti, altra concorrente del Gf.<\/span><span style=\"color: #333333; font-family: 'Segoe UI', Calibri, 'Myriad Pro', Myriad, 'Trebuchet MS', Helvetica, Arial, sans-serif; font-size: 14px; line-height: 21px; text-align: justify; background-color: #ffffff;\"><\/span><\/p>\n<p><span style=\"color: #333333; font-family: 'Segoe UI', Calibri, 'Myriad Pro', Myriad, 'Trebuchet MS', Helvetica, Arial, sans-serif; font-size: 14px; line-height: 21px; text-align: justify; background-color: #ffffff;\">Dopo la fine del suo matrimonio con il bel Daniele, Guendalina si sta riprendendo la sua vita, rimanendo sempre un&#8217;ottima mamma.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Guendalina Canessa dichiara di avere un nuovo flirt da circa due mesi. Tempo fa \u00e8 stata paparazzata con Fabio Borriello, fratello di Marco. Pare che questa sia stata una svista e che il ragazzo in questione fosse Mimmo Gravina, imprenditore napoletano, ex fidanzato di Francesca Fioretti, altra concorrente del Gf. Dopo la fine del suo [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":6752,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,41,34,5],"tags":[],"class_list":["post-6751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-intrattenimento","category-magazine","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=6751"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/6751\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/6752"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=6751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=6751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=6751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}