{"id":7049,"date":"2012-11-02T16:12:17","date_gmt":"2012-11-02T15:12:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=7049"},"modified":"2023-01-17T13:40:17","modified_gmt":"2023-01-17T12:40:17","slug":"2877-il-ruolo-del-pd-per-lalternativa-in-calabria-e-nel-paese","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2877-il-ruolo-del-pd-per-lalternativa-in-calabria-e-nel-paese\/","title":{"rendered":"&#8221;Il ruolo del PD per l\u2019alternativa in Calabria e nel Paese&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>RENDE<\/strong> &#8211; In vista delle primarie del prossimo 25 Novembre, il circolo del Partito Democratico di Rende ha organizzato un convegno sul tema: \u201cIl ruolo del PD per<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">l\u2019alternativa in Calabria e nel Paese\u201d, che sar\u00e0 concluso dal Commissario regionale, prof. Alfredo D\u2019Attorre.<\/p>\n<p style=\"text-align: justify;\">Dopo il saluto del Sindaco, avv. Vittorio Cavalcanti, sono previsti gli interventi del capogruppo del PD, in seno al Consiglio Regionale della Calabria, On. Sandro Principe e del Presidente della Provincia di Cosenza, On. Gerardo Mario Oliverio.<br \/>&#8220;Le primarie del 25 novembre &#8211; si legge nella nota del Pd &#8211; rappresentano una occasione straordinaria affinch\u00e8 la partecipazione dei cittadini favorisca il confronto, per dare contenuti programmatici all\u2019azione politica. Ci\u00f2 al fine di risolvere i problemi che stanno a cuore ai cittadini, in primo luogo la crescita economica, per dare speranza di occupazione ai giovani, unitamente al compiuto godimento dei diritti civili e dei pubblici servizi.<br \/>Per i democratici l\u2019esperienza amministrativa di Rende rappresenta un\u2019alternativa compiuta di come realizzare una citt\u00e0 ordinata e gradevole sotto il profilo del disegno urbano, ricca di verde, pulita e ben tenuta, con servizi pubblici e sociali di qualit\u00e0 e che eccelle nel campo della conoscenza, avendo saputo accogliere l\u2019Unical, e dell\u2019organizzazione produttiva, realizzando l\u2019area industriale pi\u00f9 forte della Calabria.<br \/>Questa realt\u00e0 \u00e8 da sempre apprezzata dai cittadini ed ha ottenuto significativi riconoscimenti nazionali ed internazionali&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; In vista delle primarie del prossimo 25 Novembre, il circolo del Partito Democratico di Rende ha organizzato un convegno sul tema: \u201cIl ruolo del PD per<\/p>\n","protected":false},"author":22,"featured_media":7050,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,5,44],"tags":[],"class_list":["post-7049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-old","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=7049"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7049\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/7050"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=7049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=7049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=7049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}