{"id":7172,"date":"2012-11-06T07:32:52","date_gmt":"2012-11-06T06:32:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=7172"},"modified":"2023-01-17T13:40:24","modified_gmt":"2023-01-17T12:40:24","slug":"2942-pubblicati-avvisi-per-intrattenimento-festivita-natalizie","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2942-pubblicati-avvisi-per-intrattenimento-festivita-natalizie\/","title":{"rendered":"Pubblicati avvisi per intrattenimento festivit\u00e0 natalizie"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA<\/strong> &#8211; La macchina organizzativa comunale \u00e8 al lavoro per rendere quanto pi\u00f9 possibile piacevoli ed attrattive le prossime festivit\u00e0 natalizie.&nbsp;Due diverse<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">manifestazioni di interesse sono state pubblicate a tal fine, entrambe con scadenza 12 novembre 2012.&nbsp;La prima \u00e8 relativa alle proposte culturali e di intrattenimento. L\u2019Amministrazione comunale \u2013 si legge nell\u2019avviso \u2013 nell\u2019ambito delle iniziative di rivitalizzazione e valorizzazione della citt\u00e0, intende promuovere, dal 1 dicembre 2012 al 7 gennaio 2013, la realizzazione del programma \u2018Festivit\u00e0 Natalizie 2012-2013\u2019\u201d.&nbsp;L\u2019invito \u00e8 rivolto ad una platea vasta, fatta di associazioni culturali, musicali, teatrali, di danza, agenzie, artisti, ecc\u2026., che vogliano proporre una programmazione per il periodo natalizio nelle diverse location della citt\u00e0 adeguate ad ospitare eventi.<br \/>L\u2019altra manifestazione di interesse punta invece al commercio e all\u2019esposizione nella parte antica della citt\u00e0. L\u2019Amministrazione comunale, in questo caso, invita quanti vogliano partecipare a questa nuova iniziativa commerciale \u201cin occasione delle festivit\u00e0 natalizie e nel rispetto delle tradizioni popolari\u201d. Si tratta di un progetto sperimentale per il quale il Comune \u2013 precisa il bando \u2013 conceder\u00e0 gratuitamente il suolo pubblico agli espositori e, sempre gratuitamente, gazebo ed allaccio all\u2019energia elettrica ai commercianti di articoli natalizi. Il periodo interessato va dal 20 novembre 2012 al 6 gennaio 2013.&nbsp;Entrambi gli avvisi sono consultabili e scaricabili dal sito istituzionale www.comune.cosenza.gov.it dove sono pubblicati in home page, nella sezione \u2018Bandi in scadenza\u2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La macchina organizzativa comunale \u00e8 al lavoro per rendere quanto pi\u00f9 possibile piacevoli ed attrattive le prossime festivit\u00e0 natalizie.&nbsp;Due diverse<\/p>\n","protected":false},"author":22,"featured_media":7173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-7172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=7172"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/7173"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=7172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=7172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=7172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}