{"id":7176,"date":"2012-11-06T08:01:08","date_gmt":"2012-11-06T07:01:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=7176"},"modified":"2023-01-17T13:40:24","modified_gmt":"2023-01-17T12:40:24","slug":"2944-museo-brettii-a-rassegna-comunicazione-archeologica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2944-museo-brettii-a-rassegna-comunicazione-archeologica\/","title":{"rendered":"Museo Brettii a rassegna comunicazione archeologica"},"content":{"rendered":"<p><span style=\"font-size: 11.818181991577148px; line-height: 18.651514053344727px; text-align: justify; background-color: #ffffff;\">COSENZA &#8211; Il Museo dei Brettii e degli Enotri di Cosenza parteciper\u00e0 alla \u201cRassegna del cinema e della Comunicazione Archeologica\u201d, in programma da oggi, marted\u00ec 6 novembre, fino a sabato 10 novembre, a Licodia Eubea, in provincia di Catania.&nbsp;<\/span><span style=\"font-size: 11.818181991577148px; line-height: 18.651514053344727px; text-align: justify; background-color: #ffffff;\">La manifestazione \u00e8 promossa ed organizzata dall\u2019Associazione Archeoclub d\u2019Italia di Licodia Eubea insieme alla casa di produzioni cinematografiche \u201cFine Art Cinema\u201d di Augusta che ne cura la direzione artistica.&nbsp;<\/span><span style=\"font-size: 11.818181991577148px; line-height: 18.651514053344727px; text-align: justify; background-color: #ffffff;\">Il Museo dei Brettii e degli Enotri prender\u00e0 parte alla rassegna, che \u00e8 alla sua prima edizione, con la proiezione del corto \u201cL\u2019amore riscoperto\u201d di Andrea Schiappelli e Alessandro Vanzetti, prodotto da \u201cPool Factory\u201d per lo stesso museo cosentino e regolarmente proiettato nelle sale del complesso monumentale di S.Agostino.&nbsp;<\/span><span style=\"font-size: 11.818181991577148px; line-height: 18.651514053344727px; text-align: justify; background-color: #ffffff;\">\u201cL\u2019amore riscoperto\u201d ha suscitato l\u2019interesse della rassegna di Licodia Eubea, dopo che i direttori della manifestazione, Lorenzo Daniele e Alessandra Cilio, lo avevano apprezzato alla Rassegna del cinema archeologico di Rovereto dove era stato selezionato nel 2010 e dove aveva suscitato particolare interesse. Dopo averlo visionato a Rovereto, Daniele e Cilio hanno rivolto l\u2019invito alla direttrice del Museo dei Brettii Maria Cerzoso che lo ha accolto di buon grado. Il film prodotto dall\u2019istituzione culturale cosentina figurer\u00e0 all\u2019interno del programma della seconda giornata della rassegna di Licodia Eubea, mercoled\u00ec 7 novembre. Alle 15,30 \u201cL\u2019amore riscoperto\u201d sar\u00e0 proiettato nell\u2019ex Chiesa di S.Benedetto e Santa Chiara nell\u2019ambito della sezione \u201cRagazzi e archeologia\u201d. L\u2019opera di Schiappelli e Vanzetti \u00e8 un video animato che narra la storia di una sepoltura bisoma (un uomo e una donna deposti assieme), risalente ad un momento della prima et\u00e0 del ferro (870-800 a.C. circa) e relativa alla necropoli di Torre Mordillo. La rassegna del Cinema e della Comunicazione archeologica di Licodia Eubea si tiene nel piccolo centro agricolo arroccato sui monti Iblei che gode di una tradizione archeologica di ampio respiro. La prima edizione della manifestazione \u00e8 dedicata alla memoria del prof.Antonino Di Vita, illustre archeologo scomparso di recente che proprio nel territorio licodiense ha svolto gran parte delle sue ricerche. Al prof. Di Vita l\u2019organizzazione della rassegna del cinema e della comunicazione archeologica ha intitolato anche un premio che sar\u00e0 consegnato nella giornata conclusiva del 10 novembre ad una personalit\u00e0 che ha speso la propria vita professionale nella divulgazione archeologica.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il Museo dei Brettii e degli Enotri di Cosenza parteciper\u00e0 alla \u201cRassegna del cinema e della Comunicazione Archeologica\u201d, in programma da oggi, marted\u00ec 6 novembre, fino a sabato 10 novembre, a Licodia Eubea, in provincia di Catania.&nbsp;La manifestazione \u00e8 promossa ed organizzata dall\u2019Associazione Archeoclub d\u2019Italia di Licodia Eubea insieme alla casa di produzioni [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":7177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-7176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=7176"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/7177"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=7176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=7176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=7176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}