{"id":7248,"date":"2012-11-06T16:09:12","date_gmt":"2012-11-06T15:09:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=7248"},"modified":"2023-01-17T13:40:29","modified_gmt":"2023-01-17T12:40:29","slug":"2981-cosenza-il-consiglio-si-riunisce-12-novembre","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/2981-cosenza-il-consiglio-si-riunisce-12-novembre\/","title":{"rendered":"Cosenza: il Consiglio si riunisce il 12 novembre"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #383838; font-family: Arial, 'Times New Roman', serif; font-size: 12px; line-height: normal; background-color: #ffffff;\">(ASCA) &#8211; <strong>COSENZA<\/strong> &#8211; Il Consiglio comunale di Cosenza si riunira&#8217; il prossimo 12 novembre, alle ore 15.30. Due i punti all&#8217;Ordine del Giorno: l&#8217;approvazione dello schema di <\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #383838; font-family: Arial, 'Times New Roman', serif; font-size: 12px; line-height: normal; background-color: #ffffff;\">convenzione, preliminare all&#8217;affidamento del servizio di tesoreria per il triennio 2013\/2016 mediante procedura ad evidenza pubblica.<\/span><br style=\"margin: 0px; padding: 0px; color: #383838; font-family: Arial, 'Times New Roman', serif; line-height: normal; background-color: #ffffff;\" \/><span style=\"background-color: #ffffff; color: #383838; font-family: Arial, 'Times New Roman', serif; font-size: 12px; line-height: normal;\">Il secondo punto e&#8217; sullo &#8221;stato dell&#8217;arte del DEA dell&#8217;Ospedale Civile dell&#8217;Annunziata di Cosenza&#8221;. Bipartisan la richiesta di convocazione su questo tema che porta la firma dei consiglieri Mazzuca, Frammartino, Sacco, Bozzo, Perri, Paolini e De Cicco.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(ASCA) &#8211; COSENZA &#8211; Il Consiglio comunale di Cosenza si riunira&#8217; il prossimo 12 novembre, alle ore 15.30. Due i punti all&#8217;Ordine del Giorno: l&#8217;approvazione dello schema di<\/p>\n","protected":false},"author":22,"featured_media":7249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-7248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=7248"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/7248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/7249"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=7248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=7248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=7248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}