{"id":73457,"date":"2017-01-04T08:46:11","date_gmt":"2017-01-04T07:46:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/lite-furiosa-la-sparatoria-strada-due-persone-ferite\/"},"modified":"2023-01-16T19:25:30","modified_gmt":"2023-01-16T18:25:30","slug":"129977-lite-furiosa-la-sparatoria-strada-due-persone-ferite","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/129977-lite-furiosa-la-sparatoria-strada-due-persone-ferite\/","title":{"rendered":"Lite, sparatoria per strada e due feriti a 500 metri dal commissariato, Coisp: &#8220;potenziare la struttura&#8221; (AUDIO)"},"content":{"rendered":"<p><strong>Due persone sono rimaste ferite a seguito di una sparatoria avvenuta nella serata di ieri a Catanzaro Lido, su viale Crotone, nel tratto della strada compreso fra il supermercato Crai ed il Penny Market.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>CATANZARO &#8211; Francesco <strong>Di Bona<\/strong>, fratello del defunto boss<strong> Anselmo Di Bona<\/strong>, e un <strong>cittadino di nazionalit\u00e0 marocchina<\/strong> sono rimasti feriti alle gambe, e ricoverati nell&#8217;ospedale di Catanzaro ma non sono in pericolo di vita. Le indagini sono in corso sia per stabilire il movente del litigio tra i due, sia per individuare le armi utilizzate. Secondo quanto ricostruito dagli inquirenti che indagano sull&#8217;accaduto, tra i due ci sarebbe stata una violenta lite per strada, forse legata all&#8217;attivit\u00e0 di spaccio di droga, durante la quale entrambi avrebbero estratto una pistola, esplodendo un colpo di arma da fuoco e rimanendo feriti alle gambe.<\/p>\n<h3>Potenziare il commissariato di Polizia di Catanzaro Lido<\/h3>\n<p>Dopo la sparatoria per strada, in stile far west, il segretario regionale del <strong>Coisp<\/strong>, sindacato indipendente di Polizia<strong>, Giuseppe Brugnano,<\/strong> ha ribadito la necessit\u00e0 di procedere al potenziamento del commissariato di polizia di Catanzaro Lido ai microfoni di <strong>Rlb Radioattiva<\/strong><\/p>\n<p><span style=\"color: #ff0000;\"><strong>ASCOLTA L&#8217;INTERVISTA<\/strong><\/span><br \/>\n[audio_mp3 url=&#8221;https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/01\/BRUGNANO.mp3&#8243;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-130017 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/01\/Brugnano-Coisp.jpg\" alt=\"brugnano-coisp\" width=\"600\" height=\"404\" title=\"\"><\/p>\n<p>&#8220;La sparatoria &#8211; afferma Brugnano &#8211; \u00e8 avvenuta a 500 metri dal commissariato zonale di Polizia, una struttura in sofferenza &#8211; afferma &#8211; per carenza di uomini e mezzi. Segnaliamo al nuovo questore, che si e&#8217; insediato proprio oggi, cio&#8217; che in questi anni abbiamo detto in tutte le lingue&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Due persone sono rimaste ferite a seguito di una sparatoria avvenuta nella serata di ieri a Catanzaro Lido, su viale Crotone, nel tratto della strada compreso fra il supermercato Crai ed il Penny Market.<\/p>\n","protected":false},"author":22,"featured_media":73458,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-73457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/73457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=73457"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/73457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/73458"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=73457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=73457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=73457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}