{"id":73574,"date":"2017-01-07T15:16:55","date_gmt":"2017-01-07T14:16:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/lospedale-di-cosenza-nel-mirino-di-striscia\/"},"modified":"2023-01-16T19:25:37","modified_gmt":"2023-01-16T18:25:37","slug":"130578-lospedale-di-cosenza-nel-mirino-di-striscia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/130578-lospedale-di-cosenza-nel-mirino-di-striscia\/","title":{"rendered":"L&#8217;Ospedale di Cosenza nel mirino di Striscia la Notizia (VIDEO)"},"content":{"rendered":"<h4>Destano scalpore le\u00a0grottesche condizioni in cui versa l&#8217;Annunziata.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Il diritto alla salute, un tema scottante e continuamente discusso nella nostra citt\u00e0\u00a0che, oggi, appare fortemente a rischio. Le gravissime criticit\u00e0 di tipo strutturale, organizzativo e i paurosi vuoti di organici che presenta l\u2019Ospedale dell\u2019Annunziata di Cosenza, ormai sono note a tutti. La salute a Cosenza \u00e8 un lusso. Ma la situazione appare maggiormente critica se &#8220;il malato diventa proprio l&#8217;Ospedale&#8221;. Una realt\u00e0 documentata anche da Striscia la Notizia che ieri ha messo in onda un servizio girato proprio nell&#8217;Ospedale di Cosenza. <strong>Nel reportage vengono sottolineate le &#8216;anomalie&#8217; denunciate dalla stampa locale (dal sequestro delle sale operatorie alla vicenda delle trasfusioni killer), il degrado all&#8217;interno lla struttura e le drammatiche condizioni del Pronto Soccorso.<\/strong> L&#8217;inviato ha raccolto le lamentele di pazienti, medici e volontari facendo emergere, per l&#8217;ennesima volta, la vergognosa situazione in cui versa l&#8217;Annunziata con la promessa da parte della dirigenza che i servizi saranno migliorati a breve.<br \/>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-73574-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/se-rn1-1.se.vod.msf.ticdn.it\/mp4\/2017\/01\/159755c431fa2f-07_0.mp4?_=1\" \/><a href=\"http:\/\/se-rn1-1.se.vod.msf.ticdn.it\/mp4\/2017\/01\/159755c431fa2f-07_0.mp4\" rel=\"noopener\">http:\/\/se-rn1-1.se.vod.msf.ticdn.it\/mp4\/2017\/01\/159755c431fa2f-07_0.mp4<\/a><\/video><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Destano scalpore le\u00a0grottesche condizioni in cui versa l&#8217;Annunziata.<\/p>\n","protected":false},"author":22,"featured_media":73575,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-73574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/73574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=73574"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/73574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/73575"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=73574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=73574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=73574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}