{"id":73670,"date":"2017-01-10T12:13:04","date_gmt":"2017-01-10T11:13:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/unical-arriva-mattarella-ad-inaugurare-il-45esimo-anno-accademico\/"},"modified":"2023-01-16T19:25:43","modified_gmt":"2023-01-16T18:25:43","slug":"130927-unical-arriva-mattarella-ad-inaugurare-il-45esimo-anno-accademico","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/130927-unical-arriva-mattarella-ad-inaugurare-il-45esimo-anno-accademico\/","title":{"rendered":"Unical, arriva Mattarella ad inaugurare il 45esimo anno accademico"},"content":{"rendered":"<p><strong>E&#8217; il quarto presidente della Repubblica a visitare l&#8217;Ateneo. L&#8217;inaugurazione si svolger\u00e0 il prossimo 6 febbraio.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>ARCAVACATA (CS) &#8211; Il Presidente della Repubblica, <strong>Sergio Mattarella, presenzier\u00e0 alla cerimonia d&#8217;inaugurazione del quarantacinquesimo anno accademico dell&#8217;Universit\u00e0 della Calabria<\/strong>, in programma per luned\u00ec 6 febbraio 2017 nell&#8217;aula magna del centro congressi &#8220;Beniamino Andreatta&#8221;. Sergio Mattarella &#8211; si evidenzia in una nota &#8211; <strong>sar\u00e0 il quarto Presidente della Repubblica a visitare l&#8217;Ateneo.<\/strong> Il primo, nel 1982, fu Sandro Pertini, al quale sono seguiti Carlo Azeglio Ciampi nel 2001, e Giorgio Napolitano nel 2009. &#8220;Gli aspetti organizzativi e il particolare significato dell&#8217;evento &#8211; si legge &#8211; saranno illustrati ai giornalisti dal rettore Gino Mirocle Crisci il 2 febbraio 2017, alle ore 11, nella Sala Stampa dell&#8217;Unical. Nei prossimi giorni sul portale dell&#8217;Ateneo saranno fornite le indicazioni relative alla prenotazione dei posti non compresi nell&#8217;elenco delle autorit\u00e0 previste dal cerimoniale&#8221;.<\/p>\n<p class=\"p1\"><span class=\"s1\">Subito il commento del segretario Pd Calabria, On. <strong>Ernesto Magorno<\/strong>: &#8220;Felice della presenza di Mattarella all&#8217;Unical il 6 febbraio. <strong>Il Presidente torna dopo un anno, segno di grande vicinanza per la nostra terra.<\/strong>&#8220;<\/span><\/p>\n<p class=\"p1\">\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; il quarto presidente della Repubblica a visitare l&#8217;Ateneo. L&#8217;inaugurazione si svolger\u00e0 il prossimo 6 febbraio.<\/p>\n","protected":false},"author":22,"featured_media":73671,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,7],"tags":[],"class_list":["post-73670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/73670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=73670"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/73670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/73671"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=73670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=73670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=73670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}