{"id":73740,"date":"2017-01-12T07:05:55","date_gmt":"2017-01-12T06:05:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/agente-viaggio-denunciato-utilizzo-fraudolento-carte-credito\/"},"modified":"2023-01-16T19:25:48","modified_gmt":"2023-01-16T18:25:48","slug":"131282-agente-viaggio-denunciato-utilizzo-fraudolento-carte-credito","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/131282-agente-viaggio-denunciato-utilizzo-fraudolento-carte-credito\/","title":{"rendered":"Agente di viaggio acquistava \u201cpacchetti vacanze\u201d con carte di credito intestate ad ignari titolari"},"content":{"rendered":"<p><strong>A scoprire il sistema fraudolento la Guardia di Finanza di Tropea, nell\u2019ambito dell\u2019attivit\u00e0 di prevenzione e repressione dell\u2019indebito utilizzo di strumenti di pagamento elettronico.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>TROPEA (VV) &#8211; Il <strong>titolare di un\u2019agenzia di viaggi,<\/strong> \u00e8 stato denunciato per avere effettuato acquisti di \u201c<strong>pacchetti vacanze<\/strong>\u201d utilizzando fraudolentemente, per il pagamento, numerose carte di credito intestate ad ignari titolari. Le indagini sono state avviate in seguito ad una segnalazione, effettuata da una societ\u00e0 finanziaria, che denunciava alle Fiamme Gialle l\u2019indebito utilizzo di una <strong>carta di credito<\/strong> presso una rinomata <strong>struttura alberghiera della \u201cCosta degli Dei\u201d.<\/strong><\/p>\n<p>Grazie ai successivi approfondimenti investigativi, effettuati con il supporto del Nucleo Speciale di Polizia Valutaria di Roma (che aveva gi\u00e0 attenzionato l\u2019autore della truffa) i Finanzieri hanno scoperto che la <strong>transazione<\/strong> segnalata, si inquadrava in un <strong>complesso meccanismo fraudolento,<\/strong> in virt\u00f9 del quale il responsabile della truffa, venuto in possesso dei dati delle carte di credito intestate a diversi, ignari soggetti, li aveva utilizzati per effettuare<strong> prenotazioni on-line tramite siti web specializzati.<\/strong><\/p>\n<p>L\u2019autore della truffa, infatti, esperto <strong>informatico<\/strong>, era riuscito ad impadronirsi dei numeri e dei relativi CVV (codici di verifica carta) delle carte di credito di persone, italiane e straniere, alle quali venivano illecitamente addebitati i costi delle vacanze prenotate dal titolare dell\u2019agenzia, il quale, dopo avere incamerato in contanti il corrispettivo per l\u2019acquisto dei pacchetti vacanze da parte dei clienti che realmente fruivano degli stessi, chiudeva il cerchio della truffa effettuando le prenotazioni ed utilizzando, per il pagamento, gli estremi identificativi delle carte di credito di cui era venuto in possesso.<\/p>\n<p>I Finanzieri hanno accertato che l\u2019autore della truffa ha indebitamente utilizzato i dati di diciassette carte di credito per effettuare numerose transazioni, il cui importo \u00e8 stato quantificato in oltre<strong> 28.000,00 euro, ai danni di diverse strutture alberghiere di lusso<\/strong> operanti per lo pi\u00f9 in Calabria ed in Puglia. Il soggetto \u00e8 stato deferito alla competente Autorit\u00e0 Giudiziaria per il reato di indebito utilizzo di carte di credito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A scoprire il sistema fraudolento la Guardia di Finanza di Tropea, nell\u2019ambito dell\u2019attivit\u00e0 di prevenzione e repressione dell\u2019indebito utilizzo di strumenti di pagamento elettronico.<\/p>\n","protected":false},"author":22,"featured_media":73741,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-73740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/73740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=73740"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/73740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/73741"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=73740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=73740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=73740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}