{"id":73819,"date":"2017-01-13T12:41:48","date_gmt":"2017-01-13T11:41:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/amantea-consiglieri-si-dimettono-il-sindaco-prepara-le-valigie\/"},"modified":"2023-01-16T19:25:53","modified_gmt":"2023-01-16T18:25:53","slug":"131597-amantea-consiglieri-si-dimettono-il-sindaco-prepara-le-valigie","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/131597-amantea-consiglieri-si-dimettono-il-sindaco-prepara-le-valigie\/","title":{"rendered":"Amantea, consiglieri si dimettono: il sindaco prepara le &#8220;valigie&#8221;"},"content":{"rendered":"<p><strong>Termina la guida di\u00a0Monica Sabatino dell&#8217;amministrazione comunale di Amantea, dopo le dimissioni della met\u00e0 dei suoi consiglieri.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>AMANTEA (CS) &#8211; &#8220;Non sono pi\u00f9\u00a0il sindaco di Amantea. <strong>Le dimissioni della met\u00e0\u00a0dei consiglieri eletti ha apposto la parola fine a questa esperienza.<\/strong> Ringrazio tutti, in primis proprio gli eletti che hanno iniziato con me questo percorso amministrativo e che hanno preferito compiere altre scelte e seguire altre strade, come Giusi Osso che in questo suo agire mi ha dato una grandissima lezione di vita&#8221;. Lo dice il sindaco della cittadina tirrenica, <strong>Monica Sabatino<\/strong>, in seguito alle dimissioni del consiglieri. &#8220;Ringrazio &#8211; prosegue &#8211; chi ha sostenuto la nascita e la formazione della l<strong>ista Rosa arcobaleno che, per la prima volta, ha portato al vertice dell&#8217;esecutivo una donna e una mamma<\/strong>: una circostanza impensabile solo fino a pochi anni addietro, quando le stanze delle trattative politiche erano chiuse a chi aveva anteposto il senso della famiglia a tutto il resto. <strong>Ringrazio chi non ha creduto in me e nella mia onest\u00e0<\/strong>, chi non \u00e8\u00a0stato capace di percepire le mie intenzioni, chi non ha avuto il coraggio di mostrare chi fosse in realt\u00e0.<\/p>\n<p>Ringrazio &#8211; continua &#8211; gli amici veri che non mi hanno fatto mai mancare il proprio sostegno ed anche i consiglieri di maggioranza che sono rimasti fino all&#8217;ultimo in sella, senza esitazioni, condividendo un progetto che avrebbe fatto intravedere i suoi frutti nei prossimi anni. I<strong>l nostro scopo principale era risanare l&#8217;ente comunale,<\/strong> convincendo la collettivit\u00e0 a sentirlo proprio, a partecipare al suo funzionamento, rafforzando il ruolo dell&#8217;ufficio tributi. <strong>Ringrazio i cittadini di Amantea e Campora San Giovanni: abbiamo cercato di trasmettere l&#8217;idea di una citt\u00e0 unica e unita,<\/strong> sposando le idee e le speranze delle anime che la compongono. Un ultimo ringraziamento &#8211; dice &#8211; lo rivolgo alla mia famiglia. Sono stati tanti i momenti di difficolt\u00e0\u00a0e di sconforto che sono stati superati nella tranquillit\u00e0 di un abbraccio che un genitore rivolge alla propria figlia, nella consapevolezza che ogni azione compiuta e ogni gesto \u00e8\u00a0fatto nel rispetto del prossimo e non di s\u00e8 stessi. Auguro alla mia citt\u00e0 solo il meglio e a chi verr\u00e0 dopo di me di agire con la stessa trasparenza e lo stesso amore&#8221;.<\/p>\n<p>Ora si attende lo scioglimento ufficiale del Consiglio e in tal caso il voto anticipato per eleggere il nuovo sindaco di Amantea.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><strong>LEGGI ANCHE:<\/strong><\/span><\/h3>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2209\"><span style=\"text-decoration: underline; color: #0000ff;\">Sindaco di Amantea, Monica Sabatino indagata per voto di scambio insieme al padre<\/span><\/a><\/h2>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><\/h2>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2210\"><span style=\"text-decoration: underline;\"><span style=\"color: #0000ff; text-decoration: underline;\">Caso Sabatino, i parlamentari del M5S: \u201cIl Pd sospenda subito il sindaco indagato\u201d<\/span><\/span><\/a><\/h2>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><\/h2>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2211\"><span style=\"text-decoration: underline;\"><span style=\"color: #0000ff; text-decoration: underline;\">Sindaco del Cosentino rifiuta di accogliere i migranti: \u201cNon sono razzista\u201d<\/span><\/span><\/a><\/h2>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><\/h2>\n<h2 class=\"entry-title single-post-title heading_post_title\" style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2212\"><span style=\"text-decoration: underline; color: #0000ff;\">Amantea, Sabatino: \u201cnon siamo contro i migranti ma contro un business che non \u00e8 integrazione\u201d (AUDIO)<\/span><\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Termina la guida di\u00a0Monica Sabatino dell&#8217;amministrazione comunale di Amantea, dopo le dimissioni della met\u00e0 dei suoi consiglieri.<\/p>\n","protected":false},"author":22,"featured_media":73820,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,28],"tags":[],"class_list":["post-73819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/73819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=73819"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/73819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/73820"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=73819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=73819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=73819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}