{"id":73920,"date":"2017-01-16T10:07:24","date_gmt":"2017-01-16T09:07:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/governance-poll-2016-del-sole24ore-oliverio-governatore-piu-gradito-al-sud\/"},"modified":"2023-01-16T19:25:59","modified_gmt":"2023-01-16T18:25:59","slug":"132005-governance-poll-2016-del-sole24ore-oliverio-governatore-piu-gradito-al-sud","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/132005-governance-poll-2016-del-sole24ore-oliverio-governatore-piu-gradito-al-sud\/","title":{"rendered":"Oliverio governatore pi\u00f9 &#8216;gradito&#8217; al Sud , ma perde il 10,4% dei consensi rispetto al suo insediamento"},"content":{"rendered":"<p><strong>In vetta al Governance Poll 2016 si incontrano due habitu\u00e8 delle prime posizioni, entrambi al secondo mandato. Luca Zaia, per il Veneto \u00e8 il primo, spinto in alto da un rotondo 60% di cittadini che si sentirebbero disposti a riconfermarlo alla guida della Regione<\/strong><!--more--><\/p>\n<p>ROMA &#8211; Luca Zaia. leghista, \u00e8 primo e al secondo posto, con tre punti percentuali di meno, il toscano Enrico Rossi, del Pd, con un 57% di elettori che esprimono un gradimento nei suoi confronti. I due si piazzano ai vertici del Governance Poll. Il dato sconcertante per i presidenti di Regione \u00e8 certamente quello che riguarda il presidente della Regione Sicilia, Rosario Crocetta, che entra nell\u2019anno elettorale accompagnato solo dal 28% di corregionali che si dicono pronti a confermarlo.<\/p>\n<p>Il monitoraggio di Ipr marketing, pubblicato dal Sole24Ore, mette in rilievo il gradimento dei politici locali agli occhi dei cittadini.<br \/>\nAnche se i \u201cgovernatori\u201d non sono in cima alla lista delle passioni degli italiani, e ottengono in media un tasso di gradimento del 43,3%, largamente sotto la \u201csufficienza\u201d e staccato di dieci punti abbondanti dal 53,5% raccolto in media dai sindaci.<\/p>\n<p>Questo dato generale \u00e8 per\u00f2 il frutto di due tendenze opposte: al Nord il consenso medio \u00e8 del 48%, e segna un aumento del 4% rispetto ai voti veri raccolti dai presidenti alle urne, nel Mezzogiorno invece i \u00abs\u00ec\u00bb si fermano al 39,5%, e segnalano una contrazione del 6,2% rispetto ai risultati elettorali.<\/p>\n<p>Al Sud solo <strong>Mario Oliveri<\/strong>o, si piazza al <strong>sesto posto<\/strong> con il<strong> 51% di apprezzamento<\/strong>. Oliverio, del centrosinistra, risulta infatti primo tra i governatori del sud, e addirittura sesto nella classifica nazionale sul gradimento degli amministratori stilata dall&#8217;Istituto Ipr Marketing per il Sole 24 Ore e pubblicata oggi. In particolare nella Governance poll 2017, il governatore calabrese ottiene il 51% di gradimento da parte degli elettori, in calo di 10,4 punti percentuali rispetto al giorno della sua elezioni quando era pari al 61%.<\/p>\n<p>Assieme al governatore della Basilicata, che si colloca alle sue spalle, in settima posizione, Oliverio \u00e8 l&#8217;unico tra i presidenti di Regione del sud ad oltrepassare la soglia del 50% dei giudizi positivi espressi dal campione rappresentativo consultato dall&#8217;istituto.<\/p>\n<h3>Sindaci calabresi &#8211; il consenso dei cittadini<\/h3>\n<p>Tra i sindaci calabresi il primo cittadino di Reggio Calabria, Giuseppe <strong>Falcomat\u00e0<\/strong>, si piazza al<strong> 26\/mo<\/strong> posto con il 56% di gradimento seguito da Mario <strong>Occhiuto<\/strong>, sindaco di <strong>Cosenza<\/strong> al<strong> 47\/mo con il 54%<\/strong>. E ancora Crotone che supera la sufficienza con Ugo <strong>Pugliese<\/strong>, eletto nel 2016, piazzatosi<strong> 71\/mo<\/strong> posto ottenendo il 51%, mentre <strong>Elio Costa<\/strong> \u00e8 <strong>90\/mo<\/strong> con il 49%. In <strong>cod<\/strong>a il primo cittadino di Catanzaro Sergio <strong>Abramo<\/strong> 98\/mo con il 46%.<\/p>\n<p>Sul piano nazionale al vertice della classifica c&#8217;\u00e8 la sindaca di Torino, del Movimento Cinquestelle. Chiara Appendino \u00e8 la sindaca pi\u00f9 amata. Il primo cittadino di Torino ha messo a segno una crescita di ben 7 punti e mezzo (7,4) rispetto al consenso ottenuto lo scorso anno, raggiungendo il 62%. Per contro, la sindaca di Roma pentastellata, Virginia Raggi, tra l&#8217;altro prima donna eletta a guidare Roma, registra un evidente flessione: perde circa un quarto del consenso ottenuto alle elezioni (-23,2%), scendendo al penultimo posto con il 44%. E&#8217; al terzo posto tra i sindaci pi\u00f9 amati Federico Pizzarotti, alla guida del comune di Parma, eletto con i Cinquestelle ma uscito lo scorso anno dal movimento, con il 60,5% e un aumento di quasi sei punti (5,2) rispetto al consenso dello scorso anno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In vetta al Governance Poll 2016 si incontrano due habitu\u00e8 delle prime posizioni, entrambi al secondo mandato. Luca Zaia, per il Veneto \u00e8 il primo, spinto in alto da un rotondo 60% di cittadini che si sentirebbero disposti a riconfermarlo alla guida della Regione<\/p>\n","protected":false},"author":22,"featured_media":73921,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-73920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/73920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=73920"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/73920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/73921"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=73920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=73920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=73920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}