{"id":73965,"date":"2017-01-17T06:50:57","date_gmt":"2017-01-17T05:50:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/bancarotta-fraudolenta-emesse-7-misure-cautelari-e-sequestrati-beni-per-9-milioni\/"},"modified":"2023-01-16T19:26:01","modified_gmt":"2023-01-16T18:26:01","slug":"132205-bancarotta-fraudolenta-emesse-7-misure-cautelari-e-sequestrati-beni-per-9-milioni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/132205-bancarotta-fraudolenta-emesse-7-misure-cautelari-e-sequestrati-beni-per-9-milioni\/","title":{"rendered":"Bancarotta fraudolenta, emesse 7 misure cautelari e sequestrati beni per 9 milioni"},"content":{"rendered":"<p><strong>La Guardia di Finanza sta eseguendo le misure ed il sequestro di beni, tra societ\u00e0 e conti correnti, per un valore stimato in circa nove milioni di euro.<\/strong><!--more--><\/p>\n<p>REGGIO CALABRIA &#8211; Le fiamme gialle reggine stanno eseguendo un\u2019ordinanza cautelare nei confronti di<strong> 7 soggetti per i reati di bancarotta fraudolenta,<\/strong> per aver distratto, occultato, distrutto e dissipato i beni di una societ\u00e0, causando un danno di rilevante gravit\u00e0, provocandone il fallimento. In particolare tre persone sono state assegnate ai domiciliari e altre 4 sottoposte alla misura cautelare del divieto di dimora. Inoltre \u00e8 stato disposto anche il sequestro di<strong> 4 societ\u00e0 e di conti corrente<\/strong>, riconducibili agli stessi soggetti, per un valore di circa <strong>nove milioni di euro.<\/strong><\/p>\n<p>&nbsp;<br \/>\nDalle indagini dei finanzieri \u00e8 emerso che una societ\u00e0, mediante scissione, avrebbe dato vita a diverse nuove imprese, trasferendo alle neo costituite le principali attivit\u00e0 aziendali compresi beni e attrezzature, con il fine, quindi, di depauperare il proprio patrimonio. Inoltre, sono stati individuati ingenti prelevamenti, tramite bonifici, destinati principalmente ai soci (circa 3 milioni 500 mila euro), ed in parte alle societ\u00e0 della stessa compagine, nonch\u00e9 riscontrati consistenti prelievi di contante (per 800 mila euro). <\/p>\n<p>&nbsp;<br \/>\nA causa di queste scelte si \u00e8 verificato il dissesto della societ\u00e0 e determinavano l&#8217;azzeramento del patrimonio sociale. Gli accertamenti fatti hanno consentito di individuare la cosiddetta &#8220;Testa di Legno&#8221;, il rappresentante legale pro tempore della societ\u00e0, attraverso il quale i soggetti, destinatari delle misure, operavano come amministratori di fatto. Alla luce delle acquisizioni il Gip di Palmi Massimo Minniti ha emesso le ordinanze su richiesta del sostituto procuratore Anna Pensabene, assieme ad un decreto di sequestro di quattro societ\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Guardia di Finanza sta eseguendo le misure ed il sequestro di beni, tra societ\u00e0 e conti correnti, per un valore stimato in circa nove milioni di euro.<\/p>\n","protected":false},"author":22,"featured_media":73966,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,571],"tags":[],"class_list":["post-73965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/73965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=73965"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/73965\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/73966"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=73965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=73965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=73965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}